{"id":6925,"date":"2010-07-13T19:03:56","date_gmt":"2010-07-13T18:03:56","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=6925"},"modified":"2025-03-21T11:59:22","modified_gmt":"2025-03-21T10:59:22","slug":"gps-wanderatlas-2","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/gps-wanderatlas-2-106925\/","title":{"rendered":"Wandern im Siegerland"},"content":{"rendered":"<p>Klassische Rundwanderung ums Siegerland ist Wanderung des Monats im Wanderatlas Deutschland<br \/> (Beselich, 13. Juli 2010). Das Siegerland ist der waldreichste Kreis in Deutschland. Hier entspringen Lahn, Sieg und Eder. Hier wurde mit Hauberg und Rieselwiese nachhaltiges Wirtschaften erfunden. Hier zeichnen die Ausl\u00e4ufer des Rothaargebirges eine malerische Mittelgebirgslandschaft. Und \u00fcber alledem verl\u00e4uft der Siegerland H\u00f6henring, der den Wanderer mit geh\u00f6rigen Steigungen einiges abverlangt und daf\u00fcr mit eindrucksvollen Aussichten belohnt.<!--more--><br \/> Wegen dieser guten Rahmenbedingungen stellt der Wanderatlas Deutschland auf der Webseite www.ich-geh-wandern.de den Siegerland H\u00f6henring ab Mittwoch, den 14. Juli, als Wanderung des Monats in sechs Etappen vor.<br \/> Der Wanderatlas Deutschland ist ein 2009 gestartetes Internet-Angebot, das kostenfrei Informationen f\u00fcr Tagesausfl\u00fcge und Wanderungen in die Region vorstellt. Neben Texten und Bildern sind vor allem die Darstellung von Sehensw\u00fcrdigkeiten in der dynamischen Wanderkarte sowie die M\u00f6glichkeit, Wanderungen auch als GPS-Tracks f\u00fcr mobile Navigationsger\u00e4te zu laden Merkmale, die den Wanderatlas zu einem einzigartigen Angebot im Internet macht. Seit Mai ist auch die Wanderregion Siegerland-Wittgenstein im Wanderatlas Deutschland vertreten.<br \/> Ausgangspunkt des Siegerland H\u00f6henwegs ist der Giller bei L\u00fctzel im Hilchenbacher Winkel. Von hier geht es ins Quellenland bei Netphen: Zum Ursprung von Lahn, Sieg und Eder. \u00dcber die Haincher H\u00f6he und die Kalteiche zieht sich der H\u00f6henring gen S\u00fcden bis zum Freien Grund.<br \/> Vom S\u00fcdzipfel des Siegerlands geht es weiter ins Hellerbergland und hinab ins Siegtal, das bei Kirchen erreicht wird. An der Freusburg vorbei wandert man entlang der Landesgrenze zur Rheinland-Pfalz, die das Siegerland vom Wildenburger Land trennt.<br \/> Westlich von Freudenberg erreicht der Siegerland H\u00f6henring dann die Ausl\u00e4ufer des sauerl\u00e4ndischen Ebbegebirges und knickt an der Rahrbacher H\u00f6he nach Osten, um auf der H\u00f6he des Littfelder Grunds wieder den Giller zu erreichen.<br \/> F\u00fcr den gesamten H\u00f6henring wie f\u00fcr die einzelnen Etappen stellt der Wanderatlas Deutschland ab Mittwoch die GPS-Daten kostenfrei zum Download zur Verf\u00fcgung.<\/p> <p><strong>Wanderatlas Verlag GmbH<\/strong><br \/> Steinbacher Stra\u00dfe 24<br \/> 65614 Beselich<\/p>","protected":false},"excerpt":{"rendered":"<p>Klassische Rundwanderung ums Siegerland ist Wanderung des Monats im Wanderatlas Deutschland (Beselich, 13. Juli 2010). Das Siegerland ist der waldreichste Kreis in Deutschland. Hier entspringen Lahn, Sieg und Eder. Hier wurde mit Hauberg und Rieselwiese nachhaltiges Wirtschaften erfunden. Hier zeichnen die Ausl\u00e4ufer des Rothaargebirges eine malerische Mittelgebirgslandschaft. Und \u00fcber alledem verl\u00e4uft der Siegerland H\u00f6henring, der<\/p>\n","protected":false},"author":291,"featured_media":6928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-6925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ernahrung-umwelt-natur"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/6925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=6925"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/6925\/revisions"}],"predecessor-version":[{"id":276828,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/6925\/revisions\/276828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/6928"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=6925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=6925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=6925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}