{"id":70582,"date":"2013-06-03T11:59:01","date_gmt":"2013-06-03T10:59:01","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=70582"},"modified":"2025-10-17T14:56:58","modified_gmt":"2025-10-17T13:56:58","slug":"strategie-europa-2020","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/strategie-europa-2020-1070582\/","title":{"rendered":"Strategie &#8222;Europa 2020&#8220;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-70583\" title=\"Hafen Hinterland Konferenz: Zukunft verbinden\" alt=\"Hafen Hinterland Konferenz: Zukunft verbinden\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/52925338cee984314a88534820048c7c.jpg\" width=\"150\" height=\"163\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/f54c76af9ebc0facce88157e4cea73fb.jpg\" \/>Die Verkn\u00fcpfung der Warenstr\u00f6me, die Transportm\u00f6glichkeiten des kombinierten Verkehrs von den Seeh\u00e4fen \u00fcber Sachsen-Anhalt nach Osteuropa und die Darstellung der Herausforderungen f\u00fcr den nachhaltigen Einsatz der EU-Strukturfonds in der mitteldeutschen Logistikregion im Lichte der Strategie \u201eEuropa 2020\u201c werden im Mittelpunkt der ersten europ\u00e4ischen Hafenhinterland-Konferenz vom 3. bis 5. Juli 2013 in Magdeburg stehen. \u201eWir werden Sachsen-Anhalt nicht nur als Knotenpunkt in Mitteldeutschland pr\u00e4sentieren, sondern mit unserer Landeshauptstadt Magdeburg auch eine attraktive Plattform f\u00fcr den Erfahrungsaustausch zwischen Unternehmen der europ\u00e4ischen Logistikbranche bieten\u201c, l\u00e4dt Landesverkehrsminister Thomas Webel jetzt zur Hafenhinterland-Konferenz ein.<\/p> <p><!--more-->Webel: \u201eMit dem absehbaren L\u00fcckenschluss in der A 14 von Magdeburg bis nach Schwerin und des Schieneng\u00fcterkorridors Ost wird das Land seine Zug\u00e4nge zu den K\u00fcstenh\u00e4fen noch einmal deutlich verbessern.\u201c \u201eDamit\u201c, so Webel weiter, \u201esei im Einzugsbereich des Elbkorridors ein hervorragendes Hinterland f\u00fcr die deutschen Seeh\u00e4fen entstanden.\u201c<\/p> <p>Zum Auftakt der Konferenz werden die Konferenzteilnehmer am Abend des 3. Juli 2013 im MDR-Landesfunkhaus Sachsen-Anhalt in Magdeburg zusammentreffen. Der Konferenztag am 04. Juli 2013 beginnt mit einem Impulsvortrag zur Bedeutung der Hafenhinterlandanbindung durch den Staatssekret\u00e4r im Bundesverkehrsministerium, Michael Odenwald und wird anschlie\u00dfend neben Referaten, Workshops und Unternehmensbereisungen, die beispielhaft den nachhaltigen Einsatz der EU-Strukturfonds in der mitteldeutschen Logistikregion aufzeigen werden, gef\u00fcllt.<\/p> <p>Hintergrund:<\/p> <p>Organisiert wird die Hafenhinterland-Konferenz im Auftrag des Ministeriums f\u00fcr Landesentwicklung und Verkehr von der Investitions- und Marketinggesellschaft Sachsen-Anhalt mbH (IMG) und der Logistik. Initiative des Landes, die sich nicht nur f\u00fcr die Belange der Logistik-Dienstleister sondern insbesondere f\u00fcr die Nutzer und Anwender logistischer Dienstleistungen engagiert.<\/p> <p>F\u00fcr die Moderation wurde die bekannte TV-Journalistin und Buchautorin Mira Christine M\u00fchlenhof verpflichtet, als besonderes Highlight wird Prof. Dr. Hellmuth Karasek die Veranstaltung mit einem Beitrag bereichern. Die Referenten der Workshops am Donnerstag und Freitag werden Vertreter aus \u00f6ffentlichen Institutionen der Europ\u00e4ischen Union, des Bundes und Landes als auch der Wissenschaft und Wirtschaft sein. Der Medienpartner der Hafenhinterland-Konferenz ist die Deutsche Verkehrszeitung (DVZ) der DVV Media Group, eines der Leitmedien der Logistikbranche.<\/p> <p>Weitere Informationen zum Programm und zur Registrierung finden Sie unter www.logistik-sachsen-anhalt.de\/Hafenhinterland-Konferenz<\/p> <p>Infokasten EU-Strukturfonds:<\/p> <p>Mit der EFRE- und ESF-F\u00f6rderung sollen gezielt Wachstum und Besch\u00e4ftigung in der Region verbessert werden. F\u00fcr Sachsen-Anhalt stehen im F\u00f6rderzeitraum 2007-2013 daf\u00fcr insgesamt 2,6 Milliarden Euro zur Verf\u00fcgung. Die Hafenhinterland-Konferenz des Landes Sachsen-Anhalt wird ebenfalls zu 100% aus Mitteln der EU-Strukturfonds finanziert. Hierf\u00fcr stehen insgesamt 155.000 Euro zur Verf\u00fcgung. Die EU-Strukturfonds bestehen aus dem Europ\u00e4ischen Fonds f\u00fcr regionale Entwicklung (EFRE) und dem Europ\u00e4ischen Sozialfonds (ESF). Beide sind f\u00fcr das Land Sachsen-Anhalt eine Erfolgsgeschichte f\u00fcr sich.<\/p> <p>Informationen f\u00fcr Medienvertreter:<\/p> <p>Medienvertreter k\u00f6nnen sich ab sofort \u00fcber das offizielle Registrierungstool<\/p> <p>http:\/\/www.tch-hotels.de\/teilnehmerregistrierung\/HAFENHINTERLAND\/registrierung\/ unter \u201eJournalist registrieren\u201c und Zusendung des g\u00fcltigen Presseausweises zur Konferenz und zu einer Pressereise akkreditieren.<\/p> <p>&nbsp;<\/p> <p>Firmenkontakt<br \/> IMG Investitions-und Marketinggesellschaft Sachsen-Anhalt mbH<br \/> Frauke Flenker-Manthey<br \/> Am Alten Theater 6<\/p> <p>39104 Magdeburg<br \/> Deutschland<\/p> <p>E-Mail: flenker-manthey@img-sachsen-anhalt.de<br \/> Homepage: http:\/\/www.investieren-in-sachsen-anhalt.de<br \/> Telefon: 0391\/ 568 99 71<\/p> <p>Pressekontakt<br \/> IMG Investitions-und Marketinggesellschaft Sachsen-Anhalt mbH<br \/> Frauke Flenker-Manthey<br \/> Am Alten Theater 6<\/p> <p>39104 Magdeburg<br \/> Deutschland<\/p> <p>E-Mail: flenker-manthey@img-sachsen-anhalt.de<br \/> Homepage: http:\/\/<br \/> Telefon: 0391\/ 568 99 71<\/p>","protected":false},"excerpt":{"rendered":"<p>Die Verkn\u00fcpfung der Warenstr\u00f6me, die Transportm\u00f6glichkeiten des kombinierten Verkehrs von den Seeh\u00e4fen \u00fcber Sachsen-Anhalt nach Osteuropa und die Darstellung der Herausforderungen f\u00fcr den nachhaltigen Einsatz der EU-Strukturfonds in der mitteldeutschen Logistikregion im Lichte der Strategie \u201eEuropa 2020\u201c werden im Mittelpunkt der ersten europ\u00e4ischen Hafenhinterland-Konferenz vom 3. bis 5. Juli 2013 in Magdeburg stehen. \u201eWir werden<\/p>\n","protected":false},"author":3,"featured_media":70583,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-70582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-transport-logistik"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/70582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=70582"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/70582\/revisions"}],"predecessor-version":[{"id":278005,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/70582\/revisions\/278005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/70583"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=70582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=70582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=70582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}