{"id":70829,"date":"2013-05-31T13:52:32","date_gmt":"2013-05-31T13:52:32","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=70829"},"modified":"2015-09-25T14:17:36","modified_gmt":"2015-09-25T13:17:36","slug":"aquise-von-gigs","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/aquise-von-gigs-1070829\/","title":{"rendered":"Aquise von Gigs"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Promoter Peter Konersmann praesentiert Kuenstler, Saenger und Bands\" alt=\"Promoter Peter Konersmann praesentiert Kuenstler, Saenger und Bands\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/3ce1530154c754363d1c50b002d04c58.jpg\" width=\"150\" height=\"150\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/3ce1530154c754363d1c50b002d04c58.jpg\" \/>Mehr Gigs ( Auftritte ) f\u00fcr Bands und Musiker, Ratschl\u00e4ge die sich lohnen!<\/p> <p>Wie bekomme ich mehr Gigs f\u00fcr meine Showband, Galaband und Partyband?<br \/> Es gibt sehr viele Bands. Ein kurzer Blick im Internet ( Youtube, Reverbnation usw,) d\u00fcrfte jedem Bandmitglied und Bandleader klar machen, dass der Wettbewerb um die wenigen Auftrittsm\u00f6glichkeiten sehr hoch ist.<br \/> Deswegen ist es wichtig zu wissen, was deine Band an Extras bietet.<\/p> <p><!--more-->Was macht deine Band anders als die Konkurrenz?<br \/> Erst mit diesem Wissen kannst Du Auftraggeber f\u00fcr Gigs so ansprechen, dass sie ein Interesse entwickeln.<br \/> Vergleiche deine Band mit anderen Bands, die in deiner Stadt und Umgebung spielen hilft hierbei.<br \/> Auch k\u00f6nnen dir Bekannte und Freunde, die deine Band live oder bei der Probe gesehen haben, eine ehrliche Meinung geben.<\/p> <p>Eine Demo-CD f\u00fcr Auftraggeber erstellen!<br \/> Keine Demo-CD? \/ Gibt\u00b4s nicht!<\/p> <p>Die CD ist der einzig realistische Weg, um den Auftraggeber<br \/> ( Manager ) einer Location zu beweisen, dass deine Showband den Laden rocken wird.<br \/> Es geht aber noch einen Schritt weiter bei der Erstellung einer Musik Demo-CD.<br \/> Es reicht nicht 15 Songs drauf zu schmieren und sich dann zu wundern, dass sich kein Auftraggeber meldet.<br \/> Erstelle eine super Version nur f\u00fcr die Akquise von Gigs.<br \/> Mach ein Medley deiner besten Lieder ( Songs ), die zeigen, was deine Band auf den Kasten hat. (http:\/\/www.peterkonersmann.de\/band-gerd-landes.htm)<\/p> <p>CD mit allen Angaben Beschriften!<br \/> Auftraggeber und Manager bekommen sehr viele CDs auf ihren B\u00fcrotisch.<br \/> Wenn die dann nicht auf Anhieb herausfinden k\u00f6nnen, wer die vorliegende Musik aufgenommen hat, landet die CD im Papierkorb und es wird die n\u00e4chste Partyband gebucht.<br \/> Bandname und alle Kontaktinformationen geh\u00f6ren auf die Musik CD und auf dem Layout ( Cover )<br \/> Da der Auftraggeber deine Band ja nicht kennt, kann er schwer einsch\u00e4tzen, wie sich eine gemeinsame Zusammenarbeit gestalten wird. Out ist eine gebrannte CD mit gekritzelter Schrift beschriftet.<\/p> <p>Erstelle ein Press-Kit<br \/> Neben Kontaktinformationen, Fotos und Bandnamen, darf sich auch eine Bandbiographie mit Informationen \u00fcber gespielten Musikstil, Songs und Liedern, Einfl\u00fcsse und Erfahrung finden, von Vorteil eine Setliste mit eigenen Songs und Cover aufzuf\u00fchren. Berichte aus Presse und Medien sollten im Press-Kit auch aufgef\u00fchrt sein.<br \/> Fotos, je besser diese sind, desto besser sind die Chancen einen Gig zu bekommen.<\/p> <p>Erstelle eine Liste mit Clubs und Locations!<br \/> Je mehr Gastst\u00e4tten, Locations, Hotels usw. Du findest und je l\u00e4nger die Club Liste wird, desto wahrscheinlicher, dass dabei eine Wirtschaft ( Kneipe ) oder Club und Bar findet, die dich buchen wird.<br \/> Du kannst auch andere Bands und Musiker fragen? wo sie schon \u00fcberall aufgetreten sind, schaue in die Musikmagazine Lokalmagazine, Zeitungen und ins Internet, um weitere Locations zu finden.<br \/> Wichtig ist, dass Du diese Liste kontinuierlich weiterf\u00fchrst und st\u00e4ndig um weitere Eintr\u00e4ge erweiterst.<br \/> In deiner Liste sollte neben dem Namen der Kneipe ( Gastst\u00e4tte, Clubs usw. ) noch der Name des Besitzers oder Verantwortlichen f\u00fcr die Buchungen sowie die Telefonnummer stehen.<\/p> <p>Viele K\u00fcnstler und Musiker haben Schiss, sich zu verkaufen, Potenzielle Auftraggeber anzurufen und auf Gigs anzusprechen. Aber auch die Musikszene ist in erster Linie ein Gesch\u00e4ft und die Musik nur ein Produkt.<br \/> Wer gebucht werden m\u00f6chte, der ist gut beraten, sich den Auftragsgebern und Gesch\u00e4ftsinhabern von Locations zu pr\u00e4sentieren und damit seine Party, Show, Gala, Pop, Rock und Tanzband bekannt zu machen.<\/p> <p>Gemeinsam sind wir stark!<br \/> Bands sollten schon im Vorfeld ihre gemeinsamen W\u00fcnsche und Traum Ziele kl\u00e4ren und am besten schriftlich festlegen.<br \/> Es ist wie mit den Kartoffeln, eine einzige faule Kartoffel kann die gesamte Ernte kaputt machen.Wenn ein einziges Bandmitglied kein oder weniger Interesse am gro\u00dfen Erfolg der Band hat, eine andere Vorstellung entwickelt oder etwa nicht einverstanden mit der Gage usw. ist, gehen die Probleme los. Dann kommen Ausreden f\u00fcr das nicht kommen am Stammtisch oder einer l\u00e4sst den Auftritt ( Gig ) einfach platzen. In der Folge m\u00fcssen Bands dem einen oder anderen Auftritt absagen.<\/p> <p>Anrufen lohnt sich!<br \/> Am besten, Rufe jeden Monat neue Gastgeber an, um nach Auftritte zu fragen.<br \/> Lass dich von einem Nein, nicht aus der Ruhe bringen. Es kann Hundert verschiedene Gr\u00fcnde daf\u00fcr geben.<br \/> Dein Gegen\u00fcber am Telefon hat einen schlechten Tag, die Gastst\u00e4tte ist ausgebucht, die Musik deiner Band passt nicht im Show Programm usw.<br \/> Im Telefongespr\u00e4ch solltest Du dich darauf konzentrieren, was Du und deine Band f\u00fcr den Club bieten k\u00f6nnt.<br \/> Und bleib energisch und hartn\u00e4ckig!<\/p> <p>Alle Unterlagen bringe am besten pers\u00f6nlich vorbei!<br \/> F\u00fcr Bewerbungen bei Clubs, Kneipen, Diskotheken, Feste au\u00dferhalb deiner Stadt ist das nat\u00fcrlich nicht ohne Weiteres m\u00f6glich.<br \/> Du solltest aber deine Unterlagen in deiner eigenen Stadt pers\u00f6nlich vorbeibringen. Dazu ist etwas Vorarbeit n\u00f6tig, denn Du musst zun\u00e4chst herausfinden, wer der Manager f\u00fcr die jeweilige Veranstaltung ist und wie seine Telefonnummer lautet.<\/p> <p>Ruf ihn an und fragst nach wenigen Minuten seiner Zeit, um dich als Bandleader und deine Band vorzustellen.<br \/> Der pers\u00f6nliche Kontakt kann die Entscheidung zugunsten deiner Band beeinflussen und gibt dir vielleicht den Vorsprung vor den anderen Bewerbern.<\/p> <p>Werbung ( Networking )! (http:\/\/www.peterkonersmann.de\/promotion.htm)<br \/> Es kommt nicht darauf an, was Du kannst, sondern wen Du kennst. Auf kaum eine Szene trifft das besser zu wie auf das Musikgesch\u00e4ft. Je mehr Publikum und Musiker Du kennst, je mehr Bekanntschaften zu Bands, Kneipen, Clubs, Festwirte Konzertveranstalter usw pflegst, desto h\u00f6her die Wahrscheinlichkeit mehr Auftritte f\u00fcr deine Band zu bekommen.<br \/> Aber kennen alleine hilft noch nicht. Es ist wichtig, dass diese Leute alle wissen, dass deine Band nach Gigs sucht. Diese Leute werden dich zu gegebener Zeit weiterempfehlen oder dir eine M\u00f6glichkeit anbieten, ein Konzert zu spielen.<br \/> Die Voraussetzung ist, dass deine Band sehr gut ( sympathisch ) r\u00fcber kommt und super gute Musik spielt.<\/p> <p>Mach super tolle Werbung f\u00fcr deine Band und Shows!<br \/> Wie oft bist Du schon in eine Kneipe gekommen, hast eine gute Partyband oder Orchester (http:\/\/www.peterkonersmann.de\/jazz-latin-band-manteca.htm) geh\u00f6rt und wusstest nicht, welche Band da gerade spielt?<br \/> Du musst es den Leuten einfach machen Dich und deine Band zu kennen.<br \/> Plakate aufh\u00e4ngen mit dem Bandnamen und der Telefonnummer. Verteile Flyer mit den Kontaktdaten und den n\u00e4chsten Auftritten.<br \/> Immer mal wieder den Bandnamen durch das Mikrofon durchgeben! Das hilft nicht nur um potenzielle Gigs aufzutun, es hilft zus\u00e4tzlich auch noch f\u00fcr mehr Fans und kostet nur wenig Aufwand und \u00dcberwindung sowie wenig Geld bei der Umsetzung.<br \/> Mach auch Werbung im Vorfeld f\u00fcr diesen Gig. Verlass dich nicht allein auf die Werbung, die die Location macht. Produziere eigene sehr sch\u00f6ne Flyer und sorge f\u00fcr ein volles Haus, Gastst\u00e4tte, Hotel, Club, Festzelte, Bierzelte usw.<br \/> Das macht nicht nur mehr Laune und Spa\u00df beim Spielen, das hilft auch dabei erneut gebucht zu werden.<\/p> <p>Wenn Du eine gute Show geliefert hast und die Party Stimmung gerade w\u00e4hrend deines Gigs auf dem H\u00f6hepunkt war, dann ist das der beste Zeitpunkt, um nach einer erneuten Buchung f\u00fcr Dich und deiner Band zu fragen.<\/p> <p>Mach dein eigenes Konzert mit der Band!<br \/> Wenn es denn mal gar nicht mit Auftritten laufen sollte, dann buch doch deine Band selbst und organisiere ein eigenes Konzert.<br \/> Lade auch andere Show und Galabands zum spielen ein. Diese werden gerne zusagen, denn fast alle Bands suchen immer nach neuen Auftritten und bringen ihre Fans zum Gig mit.<br \/> Ihr alle spielt dann vor einer ansehnlichen Menge von Leuten.<br \/> Am Anfang spiel jeden Auftritt<br \/> Es gibt keine zu kleinen Gigs f\u00fcr den Bandleader und seine Band die noch am Anfang ihrer Karriere stehen.<br \/> Wenn das Angebot besagt, in eine kleine Kneipe zu spielen, dann mach es!<br \/> Wenn Du deinen Job gut machst und der Location Inhaber mehr Umsatz macht wird er dich und deine Band auch \u00f6fters buchen.<br \/> Und wenn Du oft genug spielst, dann werden dich fr\u00fcher oder sp\u00e4ter auch die anderen Locations, Gastst\u00e4tten, Kneipen, Festzeltwirte usw wahrnehmen und buchen!<\/p> <p>Auf andere Konzerte der Konkurrenz gehen!<br \/> Aus Eigeninteresse die Gigs anderer Bands ansehen. Dort auf diesen Konzerten ist es eine hervorragende M\u00f6glichkeit, andere Bands kennen zu lernen und dich auszutauschen. Du kannst von den Besseren Bands lernen und siehst, was gut beim Publikum ankommt. Dazu lernst Du neue Locations und deren Belegschaft kennen.<\/p> <p>Komponist &#8211; Musikproduzent &#8211; Promotion &#8211; Management &#8211; Booking,<br \/> Peter Konersmann komponiert moderne Europaeische Musik verschiedener Musik Genres. Sein Spezialgebiet ist die Filmmusik &#8211; Filmkomponist, ein Filmkomponist entwirft Musik fuer Filme. Beruehmte Filmkomponisten druecken einen Film ihren Stempel auf, so mancher Film waere ohne den Soundtrack nicht erfolgreich geworden.<br \/> Komponist und Musikproduzent Peter Konersmann promotet Kuenstler, Bands und Musiker, komponiert und produziert Musik, Songs und Filmmusik. Promotion fuer Internationale und Nationale Kuenstler.<br \/> Kuenstler praesentieren sich auf seiner Webseite ausfuehrlich, so dass Sie als Kuenstler suchende schon vorab ein Bild machen koennen. Kuenstler geben ihre Gage mit an, was Ihnen Planungssicherheit bringt, ueber das Profil des jeweiligen Kuenstlers koennen Sie eine unverbindliche Buchungsanfrage machen. Komponist und Musikproduzent Peter Konersmann verlangt keinerlei Provisionen f\u00fcr Buchungen der Kuenstler f\u00fcr Shows, Events oder Entertainment und Veranstaltungen.<br \/> Corporate Entertainment, Wedding Bands, Jazz-Club, Deutsche Musiker, Musiker<\/p> <p>Kontakt<br \/> MrSINGSANGSONG<br \/> Peter Konersmann<br \/> Kleine Riedbruchstrasse 21<br \/> 44359 Dortmund<br \/> 0231 333238<br \/> <a href=\"mailto:support.mrsingsangsong@arcor.de\">s<\/a>upport.mrsingsangsong@arcor.de<br \/> http:\/\/www.peterkonersmann.de<\/p> <p>Pressekontakt:<br \/> Promotion Und Booking F\u00fcr K\u00fcnstler In Deutschland Und Europa www.mrsingsamgsong.de<br \/> Peter Konersmann<br \/> Kleine Riedbruchstrasse 21<br \/> 44359 Dortmund<br \/> 0231 333238<br \/> support.mrsingsangsong@arcor.de<br \/> http:\/\/www.peterkonersmann.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Mehr Gigs ( Auftritte ) f\u00fcr Bands und Musiker, Ratschl\u00e4ge die sich lohnen! Wie bekomme ich mehr Gigs f\u00fcr meine Showband, Galaband und Partyband? Es gibt sehr viele Bands. Ein kurzer Blick im Internet ( Youtube, Reverbnation usw,) d\u00fcrfte jedem Bandmitglied und Bandleader klar machen, dass der Wettbewerb um die wenigen Auftrittsm\u00f6glichkeiten sehr hoch ist.<\/p>\n","protected":false},"author":3,"featured_media":197179,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[1734],"class_list":["post-70829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musik-tanz-entertainment","tag-default"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/70829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=70829"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/70829\/revisions"}],"predecessor-version":[{"id":208321,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/70829\/revisions\/208321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/197179"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=70829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=70829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=70829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}