{"id":712,"date":"2008-11-15T17:39:10","date_gmt":"2008-11-15T16:39:10","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/24-prozent-mehr-gehalt-fur-zeitschriftenredakteure-10712\/"},"modified":"2010-11-20T08:23:42","modified_gmt":"2010-11-20T07:23:42","slug":"24-prozent-mehr-gehalt-fur-zeitschriftenredakteure","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/24-prozent-mehr-gehalt-fur-zeitschriftenredakteure-10712\/","title":{"rendered":"2,4 Prozent mehr Gehalt f\u00fcr Zeitschriftenredakteure"},"content":{"rendered":"<h4>Neuer Gehaltstarifvertrag f\u00fcr Zeitschriftenredakteure<\/h4> <p style=\"margin: 28px 0pt 10px 15px; padding: 0px; width: 150px; float: right; text-align: center\"> <span class=\"size11 mittelgrau topspace8\">Neuer Gehaltstarifvertrag f\u00fcr Zeitschriftenredakteure<\/span><\/p> <p style=\"margin-top: 25px\"><span class=\"fett\">(pressebox) Berlin, 12.11.2008<\/span> &#8211; Einen neuen Gehaltstarifvertrag f\u00fcr die rund 9.000 Zeitschriftenredakteurinnen und -redakteure haben am heutigen Mittwoch die Gewerkschaften DJV und ver.di mit dem Verband Deutscher Zeitschriftenverleger (VDZ) vereinbart.<!--more--> Nach rund sechsst\u00fcndigen Verhandlungen einigten sich die Tarifvertragsparteien darauf, dass der neue Tarifvertrag zwei Jahre bis 31. Juli 2010 gilt und 2,4 Prozent mehr Gehalt ab November und weitere 1,6 Prozent ab Oktober 2009 vorsieht. Dar\u00fcber hinaus erhalten diejenigen Redakteure im Dezember eine Einmalzahlung von 300 Euro, die am 1. August 2008 bereits bei ihrem Verlag gearbeitet haben. Neue Mitarbeiter ab 1.09. erhalten 200 Euro, ab 1.10. 100 Euro. Volont\u00e4re bekommen 50 Prozent der Einmalzahlung. Auf Teilzeitkr\u00e4fte wird sie entsprechend der Arbeitszeit aufgeteilt.<\/p> <p>Der VDZ wird keine K\u00fcndigung des Altersversorgungstarifvertrags aussprechen, die vor dem 31. Dezember 2010 wirksam wird. Verleger und Gewerkschaften kamen \u00fcberein, dass Gespr\u00e4che zum Manteltarifvertrag aufgenommen werden k\u00f6nnen. M\u00f6gliche Ver\u00e4nderungen k\u00f6nnen nicht vor dem 31. Dezember 2010 wirksam werden.<\/p> <p>Die Tarifvertragsparteien haben sich darauf verst\u00e4ndigt, Gespr\u00e4che \u00fcber Onlinet\u00e4tigkeiten in Bezug auf den Geltungsbereich des Gehaltstarifvertrags aufzunehmen.<\/p> <p>&#8222;Der Tarifabschluss ist kein Traumergebnis&#8220;, sagte DJV-Verhandlungsf\u00fchrer Hubert Engeroff, &#8222;aber mehr war vor dem Hintergrund der einsetzenden Krise auf dem Zeitschriftenmarkt nicht zu erzielen.&#8220;<\/p> <p>\u00dcber den Tarifabschluss im Zeitschriftenbereich wird der DJV-Gesamtvorstand als Gro\u00dfe Tarifkommission am 26. November in Hannover beraten. Die Erkl\u00e4rungsfrist des Abschlusses endet am 4. Dezember.<\/p> <p class=\"fett ohneunten\">Ansprechpartner:<\/p> <p class=\"ohneoben\">Herr Hendrik Z\u00f6rner<br \/> Presse- und \u00d6ffentlichkeitsarbeit<br \/> Telefon: +49 (30) 7262792-0<br \/> Fax: +49 (30) 7262792-13<br \/> Zust\u00e4ndigkeitsbereich: Pressereferent<br \/> Deutscher Journalisten-Verband<br \/> Telefon: +49 (30) 7262 7920<br \/> Fax: +49 (30) 7262 792 13<\/p>","protected":false},"excerpt":{"rendered":"<p>Neuer Gehaltstarifvertrag f\u00fcr Zeitschriftenredakteure Neuer Gehaltstarifvertrag f\u00fcr Zeitschriftenredakteure (pressebox) Berlin, 12.11.2008 &#8211; Einen neuen Gehaltstarifvertrag f\u00fcr die rund 9.000 Zeitschriftenredakteurinnen und -redakteure haben am heutigen Mittwoch die Gewerkschaften DJV und ver.di mit dem Verband Deutscher Zeitschriftenverleger (VDZ) vereinbart.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[361],"tags":[],"class_list":["post-712","post","type-post","status-publish","format-standard","hentry","category-verlagsnachrichten"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=712"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/712\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}