{"id":721,"date":"2008-11-18T12:34:01","date_gmt":"2008-11-18T11:34:01","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/zeitungen-mussen-das-web-endlich-als-chance-erkennen-10721\/"},"modified":"2022-05-24T11:51:11","modified_gmt":"2022-05-24T10:51:11","slug":"zeitungen-mussen-das-web-endlich-als-chance-erkennen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/zeitungen-mussen-das-web-endlich-als-chance-erkennen-10721\/","title":{"rendered":"Zeitungen m\u00fcssen das Web endlich als Chance erkennen"},"content":{"rendered":"<p> <font size=\"-1\"><strong>Medienmogul Murdoch fordert mehr Optimismus von Journalisten<\/strong><\/font><\/p> <table style=\"float: right; width: 168px\" border=\"0\" cellpadding=\"5\" cellspacing=\"0\"> <tr> <td align=\"center\" bgcolor=\"#ededed\"> <table border=\"0\" cellpadding=\"3\" cellspacing=\"0\" width=\"168\"> <tr> <td align=\"center\"><\/td> <\/tr> <tr> <td colspan=\"2\" class=\"txtklein\" align=\"center\"><!-- copyrighttext -->Zeitungen k\u00e4mpfen mit der Abwanderung der Leser ins Web (Foto: pixelio.de, Ernst Rose)<!-- end copyrighttext --><\/td> <\/tr> <\/table> <\/td> <\/tr> <\/table> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\"> <span class=\"txt\"> <!--PTE:ORT-->Sydney (pte\/18.11.2008\/11:47) &#8211; &#8222;Jene Untergangspropheten, die der Zeitungsindustrie den baldigen Tod prophezeien, sind irregeleitete Zyniker. Ich bin davon \u00fcberzeugt, dass die Zeitung im 21. Jahrhundert zu einer neuen H\u00f6chstform auflaufen wird&#8220;.<\/span><\/font><!--more--><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\"><span class=\"txt\"> Mit diesen Worten appellierte der US-Medienmagnat Rupert Murdoch im Rahmen einer Radioansprache der Australian Broadcasting Corporation (ABC) <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.abc.net.au\/\"  target=\"_blank\" rel=\"noopener\">http:\/\/www.abc.net.au<\/a> an die Vertreter der Zeitungsbranche. Murdoch, Vorsitzender und CEO der News Corporation, die unter anderem Zeitungstitel wie die &#8222;Sun&#8220;, die &#8222;Times&#8220; und das &#8222;Wall Street Journal&#8220; ihr Eigen nennt, forderte die Journalisten auf, mehr Optimismus f\u00fcr die Zukunft der Branche an den Tag zu legen. &#8222;W\u00e4hrend andere Wirtschaftszweige das Internet mit offenen Armen aufgenommen haben, scheinen viele Journalisten schon schwer damit besch\u00e4ftigt zu sein, an ihrem eigenen Nachruf zu arbeiten&#8220;, stellte Murdoch laut Bericht des Guardian fest. Um eine positive k\u00fcnftige Entwicklung der Zeitungswirtschaft zu erm\u00f6glichen, m\u00fcssten ihre Vertreter endlich umdenken und erkennen, welche neuen Chancen mit dem Web auf sie warten w\u00fcrden.<\/span><\/font><\/p> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\">Die gedruckten Versionen einiger Zeitungen werden nach Ansicht Murdochs in Zukunft sicherlich mit Auflager\u00fcckg\u00e4ngen rechnen m\u00fcssen. &#8222;Gleichzeitig wird es aber in anderen Bereichen wie Webseiten oder individualisierbaren E-Mail-Nachrichten und Werbung zu Zuw\u00e4chsen kommen. Im kommenden Jahrhundert \u00e4ndert sich vielleicht die Vertriebsform, das potenzielle Publikum f\u00fcr unsere Inhalte wird sich aber vervielfachen&#8220;, erkl\u00e4rte Murdoch. Um dieses Publikum auch im Internetzeitalter erfolgreich ansprechen zu k\u00f6nnen, m\u00fcssten die traditionellen Zeitungsbetriebe sich vor allem auf die Qualit\u00e4t ihres Journalismus besinnen. &#8222;Unser Gesch\u00e4ft ist es nicht, tote B\u00e4ume zu bedrucken. Wir m\u00fcssen den Lesern einen bedeutenden Journalismus und ein gro\u00dfartiges Urteilsverm\u00f6gen bieten&#8220;, stellte Murdoch klar.<\/font><\/p> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\">&#8222;Noch vor wenigen Jahren konnte eine Handvoll Redakteure dar\u00fcber entscheiden, was zur Nachricht wird und was nicht. Heute verlieren die Redaktionen diese Macht&#8220;, merkte der Medientycoon an. Das Internet biete heutzutage Zugang zu tausenden verschiedenen Nachrichtenquellen, News-Portalen und Blogs, die oft auch \u00fcber solche Dinge berichten, die eine traditionelle Zeitungsredaktion normalerweise ignoriert. Dass Nachrichtenseiten im Web den Zeitungen zunehmend die Leserschaft streitig machen, wird mittlerweile von mehreren Studien best\u00e4tigt (pressetext berichtete: http:\/\/pte.at\/pte.mc?pte=081017026). &#8222;Online-News-Seiten punkten mit Aktualit\u00e4t und interaktiven Darstellungsm\u00f6glichkeiten bei den Nutzern&#8220;, erl\u00e4utert BITKOM-Sprecher Christian Hallerberg im Gespr\u00e4ch mit pressetext fest. Wenn es um die Schnelligkeit einer Meldung geht, habe das Internet gegen\u00fcber anderen Medien eindeutig die Nase vorne. &#8222;Jedes Medium &#8211; Zeitung, TV und Radio &#8211; hat seine St\u00e4rken und damit auch seine Berechtigung. Das Internet f\u00fchrt einige dieser St\u00e4rken zusammen und hat somit strukturelle Vorteile&#8220;, meint Hallerberg.<\/font><\/p> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\">Dass das von Murdoch gezeichnete Bild der Journalisten doch etwas d\u00fcsterer ausgefallen sein d\u00fcrfte als die allgemein verbreitete Stimmung in der Branche, zeigt eine internationale Umfrage des Marktforschungsinstituts Zogby (pressetext berichtete: http:\/\/pte.at\/pte.mc?pte=081013020). Demnach blicken 85 Prozent der leitenden Zeitungsredakteure ausgesprochen hoffnungsvoll in die Zukunft. &#8222;Die heimische Zeitungslandschaft hat sich im internationalen Vergleich insgesamt sowohl bei Auflagen als auch Reichweiten stabil und gut entwickelt&#8220;, best\u00e4tigt auch Hannes Schopf, Sprecher vom Verband \u00d6sterreichischer Zeitungen (V\u00d6Z) <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/voez.at\/\"  target=\"_blank\" rel=\"noopener\">http:\/\/voez.at<\/a> , auf Anfrage von pressetext. Die Stimmung sei grunds\u00e4tzlich sehr positiv. (Ende)<br \/> <br clear=\"all\" \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.pressetext.de\/\"  target=\"_new\" rel=\"noopener\"><\/a><br \/> Aussender: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.pressetext.de\/\"  target=\"_new\" rel=\"noopener\">pressetext.austria<\/a><br \/> Redakteur:                        Markus Steiner<br \/> email: <a href=\"mailto:steiner%40pressetext.com\">steiner@pressetext.com<\/a><br \/> Tel. +43-1-81140-317   <\/font><\/p>","protected":false},"excerpt":{"rendered":"<p>Medienmogul Murdoch fordert mehr Optimismus von Journalisten Zeitungen k\u00e4mpfen mit der Abwanderung der Leser ins Web (Foto: pixelio.de, Ernst Rose) Sydney (pte\/18.11.2008\/11:47) &#8211; &#8222;Jene Untergangspropheten, die der Zeitungsindustrie den baldigen Tod prophezeien, sind irregeleitete Zyniker. Ich bin davon \u00fcberzeugt, dass die Zeitung im 21. Jahrhundert zu einer neuen H\u00f6chstform auflaufen wird&#8220;.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-721","post","type-post","status-publish","format-standard","hentry","category-allgemein-sonstiges"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=721"}],"version-history":[{"count":4,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/721\/revisions"}],"predecessor-version":[{"id":274600,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/721\/revisions\/274600"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}