{"id":74303,"date":"2013-06-18T11:50:56","date_gmt":"2013-06-18T10:50:56","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=74303"},"modified":"2013-06-18T11:50:56","modified_gmt":"2013-06-18T10:50:56","slug":"schutz-und-pflege-der-natuerlichen-barriere","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/schutz-und-pflege-der-natuerlichen-barriere-1074303\/","title":{"rendered":"Schutz und Pflege der nat\u00fcrlichen Barriere"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-74304\" title=\"Nicht immer muss es gleich ein Urlaub sein. Schon sanfte Impulse wie ein geheimnisvoller Duft, ein kurzes Innehalten, ein anregendes K\u00f6rperpeeling oder der Besuch einer Therme bringen uns manchmal in die Balance, vitalisieren K\u00f6rper und Geist, verw\u00f6hnen Haut und Sinne. \" alt=\"Nicht immer muss es gleich ein Urlaub sein. Schon sanfte Impulse wie ein geheimnisvoller Duft, ein kurzes Innehalten, ein anregendes K\u00f6rperpeeling oder der Besuch einer Therme bringen uns manchmal in die Balance, vitalisieren K\u00f6rper und Geist, verw\u00f6hnen Haut und Sinne. \" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/8d51242601269c7732f1f61a6b292cab.jpg\" width=\"186\" height=\"139\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/452061e9ee2ae9a8eb52572fef28dabd.jpg\" \/>Ein Peeling vitalisiert die Haut und weckt die Lebensgeister. Vor allem dient es zur Entfernung abgestorbener, u\u0308berschu\u0308ssiger Hautzellen. Diese lassen die Haut grau und stumpf erscheinen und behindern ihre zu\u0308gige Erneuerung. Schon im alten \u00c4gypten waren Peelings u\u0308blich. Im tu\u0308rkischen Hamam wird traditionell mit einem Handschuh aus Ziegenhaar behandelt. Heute kommen beim mechanischen Peeling unter anderem Mikrofasertu\u0308cher, harte Bu\u0308rsten, Kochsalz, Zucker, Sand, Kaffeesatz, Tonerde, zermahlende Pfirsichkerne oder Kunststoffpartikel zum Einsatz. Ein Peeling auf Urmeersalzbasis wirkt allerdings weitaus umfassender.<\/p> <p><!--more-->Die \u00e4u\u00dfere Hautschicht unserer Oberhaut &#8211; das Stratum corneum zu Deutsch Hornschicht &#8211; erneuert sich etwa alle vier Wochen. Abgestorbene Zellen wandern an die Hautoberfl\u00e4che und bilden dort Schuppen. &#8222;Bei der Entwicklung unserer Aqua Peelings haben wir darauf geachtet, dass die Salzk\u00f6rner exakt zwischen die Hautschuppen passen, um diese optimal abl\u00f6sen zu k\u00f6nnen ohne die darunter liegenden Zellen zu verletzen&#8220;, erkl\u00e4rt Dr. Marcus Wengel, Gesch\u00e4ftsfu\u0308hrer der Prof. Dr. Biener GmbH. &#8222;Unser Aqua Peeling-Salz ist daru\u0308ber hinaus angereichert mit kostbaren \u00d6len, die die Regeneration der Lipidmatrix der Oberhaut f\u00f6rdern&#8220;. Von der Haut ben\u00f6tigte Komponenten wie Lipide und Fetts\u00e4uren k\u00f6nnen dem \u00d6l entnommen und verwertet werden. Folge: seidenweiche, geschmeidige, gut durchblutete und geschu\u0308tzte Haut.<\/p> <p>\u00dcber den abl\u00f6senden Effekt hinaus stabilisiert Urmeersalz die natu\u0308rliche Hautbarriere. &#8222;Um unsere Haut vorm Austrocknen und Eindringen von Fremdstoffen und Mikroorganismen zu schu\u0308tzen, besitzt sie eine natu\u0308rliche Schutzhu\u0308lle aus Lipiden, Mineralien und Spurenelementen&#8220;, so Wengel. &#8222;Wird diese Hu\u0308lle im Alltag durch h\u00e4ufiges H\u00e4ndewaschen und den Kontakt mit der Umwelt verbraucht, verliert die Haut Wasser.&#8220; Hei\u00dft: Sie trocknet aus und wird gleichzeitig durchl\u00e4ssiger fu\u0308r unerwu\u0308nschte Eindringlinge. Im Urmeersalz enthaltene Spurenelemente wie Zink und Lithium n\u00e4hren die Hautbarriere und f\u00f6rdern ihren natu\u0308rlichen Zustand. &#8222;Die Wirkung dieser Peelings geht u\u0308ber Wellness hinaus, sie entspricht Medical Wellness.&#8220;<\/p> <p>Die Aqua Peeling-Salze gibt es mittlerweile in vielen Duftvariationen. Herb-wu\u0308rzig kommt etwa die Variante Amber\/Safran daher. Minze weckt die Lebensgeister. Aloe Vera versorgt den K\u00f6rper mit einer Extraportion Feuchtigkeit. Mango hebt die Laune. Winterfreude macht Lust auf hei\u00dfe Schokolade und Rhabarber-Erdbeere duftet einfach nach Sommer. Die Aqua Peeling-Salze erg\u00e4nzen die Vitalb\u00e4der der Prof. Dr. Biener GmbH, sind aber auch separat erh\u00e4ltlich. Sie bereichern das heimische Badezimmer ebenso wie die Produktpalette gehobener Wellness-Einrichtungen.<\/p> <p>Firmenkontakt<br \/> Prof. Dr. Biener GmbH<br \/> Dr. Marcus Wengel<br \/> Hauptstr. 30<\/p> <p>09573 Leubsdorf<br \/> Deutschland<\/p> <p>E-Mail: info@prof-dr-biener-salze.com<br \/> Homepage: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.prof-dr-biener-salze.com\" title=\" Basis unserer Aqua Peeling-Salze ist nat\u00fcrliches Urmeersalz.\" >http:\/\/www.prof-dr-biener-salze.com<\/a><br \/> Telefon: +49 (0)37291 1399-51<\/p> <p>Pressekontakt<br \/> Martina Frenzel wellness und media<br \/> Phillip Wolter<br \/> Achterstra\u00dfe 32<\/p> <p>50678 K\u00f6ln<br \/> Deutschland<\/p> <p>E-Mail: p.wolter@wellness-und-media.de<br \/> Homepage: http:\/\/www.wellness-und-media.de<br \/> Telefon: 0221 4537373<\/p>","protected":false},"excerpt":{"rendered":"<p>Ein Peeling vitalisiert die Haut und weckt die Lebensgeister. Vor allem dient es zur Entfernung abgestorbener, u\u0308berschu\u0308ssiger Hautzellen. Diese lassen die Haut grau und stumpf erscheinen und behindern ihre zu\u0308gige Erneuerung. Schon im alten \u00c4gypten waren Peelings u\u0308blich. Im tu\u0308rkischen Hamam wird traditionell mit einem Handschuh aus Ziegenhaar behandelt. Heute kommen beim mechanischen Peeling unter<\/p>\n","protected":false},"author":3,"featured_media":74304,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8805],"tags":[],"class_list":["post-74303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shopping"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/74303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=74303"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/74303\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/74304"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=74303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=74303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=74303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}