{"id":744,"date":"2008-11-30T17:09:31","date_gmt":"2008-11-30T16:09:31","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/innovatives-schutz-und-notfallsystem-fur-pflegebetten-10744\/"},"modified":"2010-07-26T14:21:25","modified_gmt":"2010-07-26T13:21:25","slug":"innovatives-schutz-und-notfallsystem-fur-pflegebetten","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/innovatives-schutz-und-notfallsystem-fur-pflegebetten-10744\/","title":{"rendered":"Innovatives Schutz- und Notfallsystem f\u00fcr Pflegebetten"},"content":{"rendered":"<p>Reduzierung des Pflegeaufwandes f\u00fcr unruhige Patienten bis zu 50 % m\u00f6glich<\/p> <p>Immer mehr pflegebed\u00fcrftigen -oft unruhigen- und altersverwirrten Menschen sowie psychisch kranken Patienten und Spastikern ist eine optimale Sicherheit nur zu gew\u00e4hrleisten, indem ihre unmittelbare Umgebung abgesichert und das Pflegebett mit einem Polstersystem ausger\u00fcstet wird. <!--more-->Der Markt bietet hier Seitengitter-Polster an, die aber nicht vor Durchrutschen, Einklemmen oder Sto\u00dfverletzungen optimal sch\u00fctzen. Besonders betroffen sind Patienten mit geringem K\u00f6rpergewicht bzw. K\u00f6rpergr\u00f6\u00dfe. Die daraus entstehenden Verletzungen f\u00fchren vielfach zu erh\u00f6hten Pflege- und Kostenintensit\u00e4ten, die es zu vermeiden gilt.<\/p> <p>In Notf\u00e4llen sind es gerade auch diese Patienten, die Rettungsma\u00dfnahmen unkooperativ gegen\u00fcber stehen und damit zu besonders schwierigen Situationen f\u00fchren. Hier gilt es eine Komplettl\u00f6sung anzustreben, die sowohl Verletzungs- als auch Transport-Sicherheit vereint.<\/p> <p>Das innovative Polstersystem \u201eCOCOON&#8220; ist eine geschlossene Schutzwanne, die einen optimalen Verletzungsschutz und eine umfassende Sicherheit im Notfall bietet. Die Matratze wird im COCOON eingebettet, so dass ein Durchrutschen unter oder zwischen den Seitengittern nicht mehr m\u00f6glich ist. Auch der Verletzungsgefahr durch unkontrollierte Bewegungen kann damit optimal vorgebeugt werden. Das Schutzsystem eignet sich f\u00fcr alle g\u00e4ngigen Pflegebetten, die Standardversion passt f\u00fcr das Grundma\u00df von 200 x 90 cm, alle anderen Ma\u00dfe sind gegen Aufpreis m\u00f6glich.<\/p> <p>Weitere Informationen \u00fcber Internet:  vitalusmedical.de   oder   Tel: 0221-7893-152<\/p>","protected":false},"excerpt":{"rendered":"<p>Reduzierung des Pflegeaufwandes f\u00fcr unruhige Patienten bis zu 50 % m\u00f6glich Immer mehr pflegebed\u00fcrftigen -oft unruhigen- und altersverwirrten Menschen sowie psychisch kranken Patienten und Spastikern ist eine optimale Sicherheit nur zu gew\u00e4hrleisten, indem ihre unmittelbare Umgebung abgesichert und das Pflegebett mit einem Polstersystem ausger\u00fcstet wird.<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[763,760,762,761,764],"class_list":["post-744","post","type-post","status-publish","format-standard","hentry","category-medizin-gesundheit-pflege-soziales","tag-aphallikerschutz","tag-cocoon-schutzsystem","tag-demenzerkrankung","tag-pflegebettpolster","tag-spastikerschutz"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=744"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/744\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}