{"id":76483,"date":"2013-06-27T14:57:03","date_gmt":"2013-06-27T13:57:03","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=76483"},"modified":"2015-03-16T12:16:14","modified_gmt":"2015-03-16T11:16:14","slug":"schnelles-und-unkompliziertes-video-cutting-fuer-den-windows-media-player","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/schnelles-und-unkompliziertes-video-cutting-fuer-den-windows-media-player-1076483\/","title":{"rendered":"Schnelles und unkompliziertes Video-Cutting f\u00fcr den Windows Media Player"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-76484\" title=\"Das PlugIn erm\u00f6glicht es Ihnen, z.B. Filmteile und Musikst\u00fccke zu speichern oder \u00fcberfl\u00fcssige Filmteile zu entfernen, w\u00e4hrend sie im Windows Media Player\u2122 geladen sind\" alt=\"Das PlugIn erm\u00f6glicht es Ihnen, z.B. Filmteile und Musikst\u00fccke zu speichern oder \u00fcberfl\u00fcssige Filmteile zu entfernen, w\u00e4hrend sie im Windows Media Player\u2122 geladen sind\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/5e07d63ec161a1270aa6027f634eb2d0.jpg\" width=\"120\" height=\"164\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/1794e287d5cc149bce7a424b0b753b53.jpg\" \/>Integration in den Windows Media Player f\u00fcr schnelle Verwendung<\/p> <p>Durch die praktische Integration in den Windows Media Player k\u00f6nnen direkt aus dem Media Player heraus Werbebl\u00f6cke entfernt, Video-Klingelt\u00f6ne erstellt oder kurze YouTube-Videos geschnitten werden. Praktisch ist ein schnelles unkompliziertes Video-Cutting auch dann, wenn man etwa bestimmte Szenen in Kinderfilmen vor dem Anschauen herausschneiden m\u00f6chte oder gro\u00dfe Filme auf mehrere kleine aufteilen m\u00f6chte, um sie auf CD zu brennen oder per E-Mail zu verschicken.<\/p> <p><!--more-->Mit einer neu gestalteten Oberfl\u00e4che wurde die Handhabung in der neuen Version weiter vereinfacht. So erlaubt nun eine visuelle Zeitleiste mit einer Frame-genauen Navigation daf\u00fcr, dass sehr intuitiv die Stelle zum Schneiden ausgew\u00e4hlt oder direkt zu gew\u00fcnschten Stellen gesprungen werden kann. Au\u00dferdem k\u00f6nnen mit der Multi-Cutting-Option alle Stellen, die gel\u00f6scht werden sollen, gleichzeitig ausgew\u00e4hlt werden, um sie mit einem Befehl auf einmal schneiden zu k\u00f6nnen. Auf Wunsch extrahiert der WMP Trimmer Plugin dabei auch reine Videos ohne Ton, als auch reine Audiospuren.<\/p> <p>Preise, Betriebssysteme und Verf\u00fcgbarkeit<\/p> <p>Das &#8218;WMP Trimmer Plugin 3.0&#8216; kann \u00fcber die Webseite ( www.solveigmm.com\/de\/produkte\/wmp-trimmer-plugin ) heruntergeladen und anschlie\u00dfend getestet werden. Bei Gefallen kann eine Home-Edition-Lizenz f\u00fcr 29,69 Euro inkl. MwSt. oder eine Business-Edition-Lizenz f\u00fcr 49,95 Euro zzgl. MwSt. erworben werden. Das Plugin kann f\u00fcr alle Windows Media Player ab Windows XP oder h\u00f6her installiert werden.<\/p> <p>Firmenkontakt<br \/> Solveig Multimedia<br \/> Olga Krovyakova<br \/> Akademicheskij Avenue 10\/3<\/p> <p>634055 Tomsk<br \/> Russland<\/p> <p>E-Mail: de-info@solveigmm.com<br \/> Homepage: http:\/\/www.solveigmm.com\/de<br \/> Telefon: +7 382 249-2609<\/p> <p>Pressekontakt<br \/> Prolog Communications GmbH<br \/> Matthias Scholz-D\u00fcrrschmied<br \/> Sendlinger Stra\u00dfe 24<\/p> <p>80331 M\u00fcnchen<br \/> Deutschland<\/p> <p>E-Mail: solveigmm@prolog-pr.com<br \/> Homepage: http:\/\/www.prolog-pr.com<br \/> Telefon: +49 89 800 77-0<\/p>","protected":false},"excerpt":{"rendered":"<p>Integration in den Windows Media Player f\u00fcr schnelle Verwendung Durch die praktische Integration in den Windows Media Player k\u00f6nnen direkt aus dem Media Player heraus Werbebl\u00f6cke entfernt, Video-Klingelt\u00f6ne erstellt oder kurze YouTube-Videos geschnitten werden. Praktisch ist ein schnelles unkompliziertes Video-Cutting auch dann, wenn man etwa bestimmte Szenen in Kinderfilmen vor dem Anschauen herausschneiden m\u00f6chte oder<\/p>\n","protected":false},"author":3,"featured_media":76484,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-76483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-computer-und-videospiele"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/76483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=76483"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/76483\/revisions"}],"predecessor-version":[{"id":178118,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/76483\/revisions\/178118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/76484"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=76483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=76483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=76483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}