{"id":770,"date":"2008-12-15T12:35:43","date_gmt":"2008-12-15T11:35:43","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/e-books-revolutionieren-buchhandel-10770\/"},"modified":"2022-05-24T11:51:12","modified_gmt":"2022-05-24T10:51:12","slug":"e-books-revolutionieren-buchhandel","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/e-books-revolutionieren-buchhandel-10770\/","title":{"rendered":"E-Books revolutionieren Buchhandel"},"content":{"rendered":"<p><font size=\"-1\"><strong>&#8222;Vielen ist nicht klar, welche Umw\u00e4lzungen sich f\u00fcr Branche ergeben&#8220;<\/strong><\/font><\/p> <table style=\"float: right; width: 168px\" border=\"0\" cellpadding=\"5\" cellspacing=\"0\"> <tr> <td align=\"center\" bgcolor=\"#ededed\"> <table border=\"0\" cellpadding=\"3\" cellspacing=\"0\" width=\"168\"> <tr> <td align=\"center\"><\/td> <\/tr> <tr> <td colspan=\"2\" class=\"txtklein\" align=\"center\"><!-- copyrighttext -->Leseger\u00e4te wie Sonys Reader erfreuen sich einer zunehmenden Beliebtheit (Foto: sony.com)<!-- end copyrighttext --><\/td> <\/tr> <\/table> <\/td> <\/tr> <\/table> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\"> <span class=\"txt\"> <!--PTE:ORT--> Frankfurt am Main (pte\/12.12.2008\/13:40) &#8211; Die zunehmende Verbreitung von elektronischen B\u00fccherleseger\u00e4ten, sogenannten E-Books, wird den Buchhandel in den kommenden Jahren vor eine enorme Herausforderung stellen. Viele Kollegen sind sich gar nicht im Klaren dar\u00fcber, welche Umw\u00e4lzungen sich dadurch f\u00fcr die Branche ergeben k\u00f6nnen.<\/span><\/font><!--more--><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\"><span class=\"txt\"> Zu dieser Einsch\u00e4tzung kommt Stephan Jaenicke, Vorstandsmitglied des B\u00f6rsenvereins des Deutschen Buchhandels <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.boersenverein.de\/\"  target=\"_blank\" rel=\"noopener\">http:\/\/www.boersenverein.de<\/a> , in einem aktuellen Interview mit dem Wirtschaftsmagazin &#8222;Der Handel&#8220;. &#8222;Am Anfang werden E-Books sicher nur von einem exklusiven Nutzerkreis verwendet werden, mittelfristig werden sie aber sicher signifikante Marktanteile erobern&#8220;, stellt Jaenicke fest. Die E-Books-Entwicklung werde auf jeden Fall kommen. &#8222;Es ist nur die Frage, ob man den Markt hier komplett den gro\u00dfen Playern wie Amazon und Google \u00fcberl\u00e4sst oder auch selbst mitspielen m\u00f6chte&#8220;, so Jaenicke.<\/span><\/font><\/p> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\">Bisher seien Buchinhalte praktisch immer untrennbar mit dem Tr\u00e4germedium, dem k\u00f6rperlichen Buch, verbunden gewesen. Nun gehe es pl\u00f6tzlich nicht mehr um das Medium, sondern nur noch um den Inhalt. &#8222;Wenn man diese Entwicklung konsequent weiterdenkt, wird man sich irgendwann sicherlich die Frage stellen m\u00fcssen, wozu man in Zukunft \u00fcberhaupt noch einen station\u00e4ren Buchhandel braucht, wenn man doch alles im Internet erledigen kann&#8220;, erkl\u00e4rt Jaenicke. Wenn das gedruckte Buch in ferner Zukunft einmal eine Art Nischenprodukt sein sollte, h\u00e4tten kleine unabh\u00e4ngige Buchhandlungen bessere Chancen, es als &#8218;Kultprodukt&#8216; zu vermarkten als die gro\u00dfen Ketten. F\u00fcr die Branche sei es aber generell dringend notwendig, sich schnell mit dem Thema E-Books auseinanderzusetzen. &#8222;Viele befassen sich deshalb nicht mit dem Thema, weil sie f\u00fcrchten, dass jede Aktivit\u00e4t in Bezug auf E-Books die kommenden Entwicklungen nur beschleunigen werden&#8220;, meint Jaenicke.<\/font><\/p> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\">Wenn Buchinhalte erst einmal digital vorliegen w\u00fcrden, nehme auch die Gefahr von Raubkopien und illegalen Downloads zu. &#8222;\u00c4hnlich wie bei den Musikdownloads wird sich mancher Nutzer fragen, warum er f\u00fcr Buchinhalte Geld bezahlen soll, wenn er sie auch kostenlos irgendwo illegal herunterladen kann&#8220;, ist Jaenicke \u00fcberzeugt. &#8222;Der illegale E-Book-Markt erreicht in Internettauschb\u00f6rsen derzeit zwar noch nicht die hohen Angebotszahlen der H\u00f6rbuch- oder der Musikbranche. Dennoch wird in den n\u00e4chsten Jahren auch dieser illegale Markt explodieren&#8220;, betont Bj\u00f6rn Frommer, Experte f\u00fcr Urheberrecht und Mitglied der Arbeitsgruppe Piraterie im B\u00f6rsenverein des Deutschen Buchhandels, gegen\u00fcber pressetext.<\/font><\/p> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\">&#8222;Ich bin mir sicher, dass der technologische Druck die Situation f\u00fcr die Literatur- und Verlagsbranche noch versch\u00e4rfen wird&#8220;, erg\u00e4nzt Frommer. Mitverantwortlich hierf\u00fcr sei nicht zuletzt auch die noch nicht ausreichend gekl\u00e4rte rechtliche Lage zu Ver\u00f6ffentlichungen im Internet. Auch von Autorenseite w\u00fcrden die Verlage k\u00fcnftig zunehmend unter Druck geraten. &#8222;Das Buch wird nat\u00fcrlich nicht untergehen. Die Branche muss sich aber auf eine steigende Zahl von illegalen und zumeist kostenlosen Online-Kopien einstellen und ihre Strategien entsprechend anpassen&#8220;, so Frommer abschlie\u00dfend. (Ende)<br \/> <br clear=\"all\" \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.pressetext.de\/\"  target=\"_new\" rel=\"noopener\"><\/a><br \/> Aussender: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.pressetext.de\/\"  target=\"_new\" rel=\"noopener\">pressetext.deutschland<\/a><br \/> Redakteur:                        Markus Steiner<br \/> email: <a href=\"mailto:steiner%40pressetext.com\">steiner@pressetext.com<\/a><br \/> Tel. +43-1-81140-317   <\/font><\/p>","protected":false},"excerpt":{"rendered":"<p>&#8222;Vielen ist nicht klar, welche Umw\u00e4lzungen sich f\u00fcr Branche ergeben&#8220; Leseger\u00e4te wie Sonys Reader erfreuen sich einer zunehmenden Beliebtheit (Foto: sony.com) Frankfurt am Main (pte\/12.12.2008\/13:40) &#8211; Die zunehmende Verbreitung von elektronischen B\u00fccherleseger\u00e4ten, sogenannten E-Books, wird den Buchhandel in den kommenden Jahren vor eine enorme Herausforderung stellen. Viele Kollegen sind sich gar nicht im Klaren dar\u00fcber,<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-770","post","type-post","status-publish","format-standard","hentry","category-journalismus-medien-publizistik"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=770"}],"version-history":[{"count":2,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/770\/revisions"}],"predecessor-version":[{"id":274605,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/770\/revisions\/274605"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}