{"id":77609,"date":"2013-07-02T10:43:20","date_gmt":"2013-07-02T10:43:20","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=77609"},"modified":"2013-07-02T14:24:07","modified_gmt":"2013-07-02T13:24:07","slug":"kleiner-chip-grosse-wirkung","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/kleiner-chip-grosse-wirkung-1077609\/","title":{"rendered":"Kleiner Chip &#8211; Gro\u00dfe Wirkung"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Hunde m\u00fcssen draussen bleiben - und sind damit unbeaufsichtigt\" alt=\"Hunde m\u00fcssen draussen bleiben - und sind damit unbeaufsichtigt\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/066a5c45db54c69d5f7343b55f4d59b7.jpg\" width=\"150\" height=\"150\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/066a5c45db54c69d5f7343b55f4d59b7.jpg\" \/>Deutsches Tierschutzb\u00fcro warnt vor Hundediebstahl<\/p> <p>Immer wieder werden vor Gesch\u00e4ften angebundene Hunde geklaut. Das Deutsche Tierschutzb\u00fcro e.V. r\u00e4t daher allen Hundehaltern, gut auf ihre Hunde aufzupassen und diese chippen zu lassen.<br \/> Es ist der Alptraum eines jeden Hundehalters: Ein kurzer Besuch im Supermarkt und pl\u00f6tzlich ist der vor der T\u00fcr angebundene Hund spurlos verschwunden. Dem Deutschen Tierschutzb\u00fcro e.V. werden immer wieder solche F\u00e4lle gemeldet. Betroffen sind zumeist Welpen und Hunde kleiner Rassen.<\/p> <p><!--more-->Stefan Klippstein, gelernter Tierpfleger und Sprecher des Deutschen Tierschutzb\u00fcros e.V., erkl\u00e4rt: &#8222;Wir gehen davon aus, dass es sich bei den Diebst\u00e4hlen zumeist um spontane, un\u00fcberlegte Taten handelt, die von psychisch labilen Personen begangen werden. Vermutlich wecken besonders junge oder niedlich aussehende Hunde bei ihnen Begehrlichkeiten, denen sie un\u00fcberlegt nachgeben. Ein anderer Grund k\u00f6nnte auch sein, dass die Tiere bewusst geklaut werden, um sie anschlie\u00dfend via Internet zu verkaufen. &#8222;Einige Rassewelpen werden im Internet f\u00fcr mehr als tausend Euro angeboten&#8220;, so Klippstein, der selbst regelm\u00e4\u00dfig die einschl\u00e4gigen Webportale nach dubiosen Anzeigen durchst\u00f6bert und diese dann anzeigt.<\/p> <p>Betroffenen Hundehaltern r\u00e4t Klippstein zur Vorsicht: &#8222;Man sollte den Hund nicht zu lange alleine vor einem Gesch\u00e4ft sitzen lassen und m\u00f6glichst immer wieder ein Auge auf das Tier werfen, um zu sehen, ob sich jemand auff\u00e4llig mit ihm besch\u00e4ftigt.&#8220;<\/p> <p>Zudem r\u00e4t das Deutsche Tierschutzb\u00fcro e.V. ausdr\u00fccklich dazu, alle Hunde chippen und registrieren zu lassen. &#8222;Nur so ist eine zweifelsfreie Identifizierung des Tieres und damit auch eine R\u00fcckvermittlung m\u00f6glich&#8220;, so der Tierpfleger abschlie\u00dfend.<\/p> <p>Deutsches Tierschutzb\u00fcro e.V. &#8211; Wir geben Tieren eine Stimme!<\/p> <p>Reduziert auf ihre Funktion als Nahrungsmittellieferant, Messinstrument oder lebende Zielscheibe leiden in Deutschland Millionen Tiere. Unzureichende Rechtsvorschriften und mangelhafter Vollzug f\u00fchren dazu, dass f\u00fcr jeden Laien offensichtlich, Tierqu\u00e4lerei, ob in der industriellen Massentierhaltung oder in Tierversuchslaboren, Alltag und zudem vollkommen legal ist. Auch grausame und \u00fcberholte Traditionen wie die Hobbyjagd oder das bet\u00e4ubungslose Sch\u00e4chten haben hierzulande bis heute Bestand.<br \/> Das Deutsche Tierschutzb\u00fcro e.V. k\u00e4mpft gegen diese allt\u00e4gliche Tierqual. Wir haben es uns zur Aufgabe gemacht den Tieren ein Anwalt zu sein, ihnen eine Stimme zu geben und f\u00fcr ihre Rechte zu streiten.<br \/> Wir dokumentieren Tierqu\u00e4lerei und machen sie \u00f6ffentlich, \u00fcben mit spektakul\u00e4ren Aktionen und intensiver Medienarbeit Druck auf die verantwortlichen Politiker aus und greift direkt ein, um Tierleben zu retten.<br \/> Mit unseren Informations- und Aufkl\u00e4rungskampagnen versuchen wir gerade die Menschen zu erreichen, die sich bislang nur wenig Gedanken \u00fcber Tierschutz oder die Herkunft tierischer Produkte gemacht haben. Denn nur wenn die Mehrheit der Verbraucher und W\u00e4hler sich gegen tierqu\u00e4lerisch erzeugte Produkte entscheidet und bessere Gesetze und strengere Kontrollen fordert, wird sich die Situation der Tiere \u00e4ndern.<br \/> Dass dies schon bald der Fall ist, daran arbeiten wir t\u00e4glich. Unser Ziel ist es, dass Tierheime und Gnadenh\u00f6fe irgendwann leer stehen und unsere Arbeit \u00fcberfl\u00fcssig wird.<\/p> <p>Kontakt:<br \/> Deutsches Tierschutzb\u00fcro e.V.<br \/> Stefan Klippstein<br \/> An Gro\u00df Sankt Martin 6\/206<br \/> 50667 K\u00f6ln<br \/> 0221-20463862<br \/> Info@tierschutzbuero.de<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.tierschutzbuero.de\" title=\"das deutsche Tierschutzb\u00fcro im Netz\" >http:\/\/www.tierschutzbuero.de<\/a><\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Deutsches Tierschutzb\u00fcro warnt vor Hundediebstahl Immer wieder werden vor Gesch\u00e4ften angebundene Hunde geklaut. Das Deutsche Tierschutzb\u00fcro e.V. r\u00e4t daher allen Hundehaltern, gut auf ihre Hunde aufzupassen und diese chippen zu lassen. Es ist der Alptraum eines jeden Hundehalters: Ein kurzer Besuch im Supermarkt und pl\u00f6tzlich ist der vor der T\u00fcr angebundene Hund spurlos verschwunden. Dem<\/p>\n","protected":false},"author":3,"featured_media":197121,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8807],"tags":[1734],"class_list":["post-77609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tiere","tag-default"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/77609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=77609"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/77609\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/197121"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=77609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=77609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=77609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}