{"id":816,"date":"2009-01-23T08:45:33","date_gmt":"2009-01-23T07:45:33","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/zeitschriften-halten-reichweiten-stabil-10816\/"},"modified":"2022-05-24T11:51:14","modified_gmt":"2022-05-24T10:51:14","slug":"zeitschriften-halten-reichweiten-stabil","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/zeitschriften-halten-reichweiten-stabil-10816\/","title":{"rendered":"Zeitschriften halten Reichweiten stabil"},"content":{"rendered":"<p><font size=\"-1\"><strong>Von Krise laut Media-Analyse keine Spur <\/strong><\/font><\/p> <table style=\"float: right; width: 168px\" border=\"0\" cellpadding=\"5\" cellspacing=\"0\"> <tr> <td align=\"center\" bgcolor=\"#ededed\"> <table border=\"0\" cellpadding=\"3\" cellspacing=\"0\" width=\"168\"> <tr> <td align=\"center\"><\/td> <\/tr> <tr> <td colspan=\"2\" class=\"txtklein\" align=\"center\"><!-- copyrighttext --> (Foto: pixelio.de\/ \tRolf van Melis)<!-- end copyrighttext --><\/td> <\/tr> <\/table> <\/td> <\/tr> <\/table> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\"> <span class=\"txt\"> <!--PTE:ORT-->Frankfurt (pte\/22.01.2009\/06:10) &#8211; Entgegen der allgemeinen Printflaute entwickeln sich die Reichweiten auf dem deutschen Zeitschriftenmarkt weiterhin stabil. Wie aus den aktuellen Daten der Arbeitsgemeinschaft Media-Analyse (ag.ma) agma-mmc.de hervorgeht, blieb die Zeitschriftennutzung in den vergangenen Monaten insgesamt auf hohem Niveau.<\/span><\/font><!--more--><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\"><span class=\"txt\"> \u00dcber eine Viertel Mrd. bzw. 275 Mio. Zeitschriften wurden in Deutschland pro Erscheinungsintervall (w\u00f6chentlich\/14-t\u00e4gig\/monatlich) gelesen. Das bedeutet umgerechnet, dass jeder Deutsche ab 14 Jahren im Schnitt vier Magazine konsumiert. &#8222;Zeitschriften haben nat\u00fcrlich auch zu k\u00e4mpfen, sowohl mit der Auflage als auch mit dem Anzeigengesch\u00e4ft. Wir werten es aber als positives Zeichen f\u00fcr die Branche, dass die Reichweiten trotzdem sehr stabil bleiben&#8220;, sagt Michael Walter, Vorstand Zeitschriften der ag.ma, im Gespr\u00e4ch mit pressetext.<\/span><\/font><\/p> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\">Die Gesamtreichweite der in der ma 2009 Pressemedien I erfassten Titel konnte sogar einen leichten Zuwachs von 60,7 auf 60.8 Mio. Leser erzielen. Die Anzahl der ausgewiesenen Zeitschriften sank gleichzeitig von 170 auf 164. Im Detail haben 75 Titel davon ihre Reichweite ausgebaut, 21 blieben stabil und 67 Zeitschriften b\u00fc\u00dften an Reichweite ein. &#8222;Das Leserinteresse ist ungebrochen stark, auch wenn die Auflagen schw\u00e4cheln&#8220;, so Walter. Der Grund daf\u00fcr liegt offenbar in der wirtschaftlichen Krise. In solchen Zeiten werden zwar gelegentlich weniger Ausgaben vom Nutzer gekauft, daf\u00fcr aber die erworbenen intensiver gelesen. Auch die Weitergabe an andere erfolgt, was die Reichweite wiederum positiv beeinflusst. &#8222;Die Reichweite w\u00e4re eine gute Basis f\u00fcr ein stabiles Anzeigengesch\u00e4ft 2009. Allerdings ist zu bef\u00fcrchten, dass die allgemeine wirtschaftliche Krise das \u00fcberlagern wird&#8220;, meint Walter gegen\u00fcber pressetext.<\/font><\/p> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\">Die gr\u00f6\u00dfte Reichweite \u00fcberhaupt erzielte &#8222;ADAC Motorwelt&#8220; mit 18,48 Mio. Lesern, dahinter folgen das Supplement &#8222;rtv&#8220; auf Platz zwei und &#8222;Bild am Sonntag&#8220; auf Platz drei. Ebenfalls in den Top 20 der am meisten gelesenen Zeitschriften finden sich &#8222;Stern&#8220;, &#8222;Der Spiegel&#8220;, &#8222;Focus&#8220;, &#8222;Computer Bild&#8220; und &#8222;GEO&#8220;. Zu den st\u00e4rksten Verlieren z\u00e4hlen unter anderem einige Vertreter aus dem Bereich M\u00e4nnerzeitschriften. So haben sowohl &#8222;GQ&#8220; als auch &#8222;FHM&#8220; deutlich an Leserschaft eingeb\u00fc\u00dft. Weniger Interesse riefen aber auch einige Titel aus dem Bereich Wissensmagazine hervor.<\/font><\/p> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\">In den einzelnen Gattungen zeigt sich die Reichweitenentwicklung konstant und krisenresistent. Im Vergleich zur vorangegangenen Erhebung (pressetext berichtete: http:\/\/pte.at\/pte.mc?pte=080723017) erzielten Sportzeitschriften die st\u00e4rksten Zuw\u00e4chse. Signifikant an Reichweite verloren haben hingegen die Bereiche Musik- und Jugendzeitschriften, Lifestyle\/Stadtmagazine\/Erotik, Wissenschaft\/Technik\/Kultur sowie Unterhaltungselektronik\/Computer und Wirtschaftspresse. Einzelne Verluste lassen sich laut Media-Analyse aber auch darauf zur\u00fcckf\u00fchren, dass die aktuelle Erhebung weniger Titel in dem Segment ausweist als die letzte aus dem Vorjahr. &#8222;Generell kann man sagen, dass gut gepflegte Marken eigentlich sehr stabil bleiben, auch in schwierigen M\u00e4rkten&#8220;, erkl\u00e4rt Walter. Innerhalb der einzelnen Segmente gebe es aufgrund des Konkurrenzkampfs aber nat\u00fcrlich auch immer wieder starke Wechsel. (Ende)<br \/> <br clear=\"all\" \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.pressetext.de\/\"  target=\"_new\" rel=\"noopener\"><\/a><br \/> Aussender: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.pressetext.de\/\"  target=\"_new\" rel=\"noopener\">pressetext.deutschland<\/a><br \/> Redakteur:                        Claudia Zettel<br \/> email: <a href=\"mailto:zettel%40pressetext.com\">zettel@pressetext.com<\/a><br \/> Tel. +43-1-81140-314   <\/font><\/p>","protected":false},"excerpt":{"rendered":"<p>Von Krise laut Media-Analyse keine Spur (Foto: pixelio.de\/ Rolf van Melis) Frankfurt (pte\/22.01.2009\/06:10) &#8211; Entgegen der allgemeinen Printflaute entwickeln sich die Reichweiten auf dem deutschen Zeitschriftenmarkt weiterhin stabil. Wie aus den aktuellen Daten der Arbeitsgemeinschaft Media-Analyse (ag.ma) agma-mmc.de hervorgeht, blieb die Zeitschriftennutzung in den vergangenen Monaten insgesamt auf hohem Niveau.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-816","post","type-post","status-publish","format-standard","hentry","category-marketing-werbung-pr-design"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=816"}],"version-history":[{"count":3,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/816\/revisions"}],"predecessor-version":[{"id":274612,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/816\/revisions\/274612"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}