{"id":839,"date":"2009-02-10T10:20:37","date_gmt":"2009-02-10T09:20:37","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/das-10-jahrige-country-jubilaum-startet-in-die-zweite-runde-10839\/"},"modified":"2012-09-24T15:30:38","modified_gmt":"2012-09-24T14:30:38","slug":"das-10-jahrige-country-jubilaum-startet-in-die-zweite-runde","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/das-10-jahrige-country-jubilaum-startet-in-die-zweite-runde-10839\/","title":{"rendered":"Das 10-j\u00e4hrige COUNTRY-Jubil\u00e4um startet in die zweite Runde"},"content":{"rendered":"<p>COUNTRY &#8211; das Premium Magazin f\u00fcr l\u00e4ndliche Lebensart aus dem Hamburger JAHRESZEITEN VERLAG startet in die zweite Runde: <!--more-->Ein R\u00fcckblick auf das Landleben von Prominenten und Gewinne im Gesamtwert von 18.500 Euro &#8211; Hauptpreis ist eine Kreuzfahrt rund um die Britischen Inseln &#8211; machen COUNTRY 2\/09 noch interessanter. Das Jubil\u00e4ums-Special bietet zus\u00e4tzliche Anreize, um den Erfolg des 4. Quartals 2008 mit einem Zuwachs<br \/> von 35 Prozent im Einzelverkauf fortzusetzen.<\/p> <p>Sehnsucht auf den Fr\u00fchling weckt die neue Ausgabe mit Themen, die dem Land-Trend und der Lust aufs nat\u00fcrliche<br \/> Leben entsprechen: den pr\u00e4chtigen Garten einer Expertin f\u00fcr Zwiebelblumen, erfrischende Ideen f\u00fcr Blumenk\u00e4sten als Gem\u00fcsebeet oder Duftoase, entspanntes Leben in alten H\u00e4usern, besinnliche Urlaube im Kloster und die besten Brotrezepte.<br \/> Hamburg, 6. Februar 2009<br \/> _____________________________________________________________<br \/> Pressekontakt: Mona Burmester, Presse und \u00d6ffentlichkeitsarbeit JAHRESZEITEN VERLAG, Tel. 040\/2717-2493, Fax 040\/2717-2063, E-Mail: presse@jalag.de<\/p>","protected":false},"excerpt":{"rendered":"<p>COUNTRY &#8211; das Premium Magazin f\u00fcr l\u00e4ndliche Lebensart aus dem Hamburger JAHRESZEITEN VERLAG startet in die zweite Runde:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-839","post","type-post","status-publish","format-standard","hentry","category-allgemein-sonstiges"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=839"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/839\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}