{"id":84,"date":"2008-02-28T07:29:31","date_gmt":"2008-02-28T06:29:31","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/compumatica-entwickelte-neues-verschlusselungsgerat-fur-mobilen-einsatz\/"},"modified":"2010-07-26T14:23:29","modified_gmt":"2010-07-26T13:23:29","slug":"compumatica-entwickelte-neues-verschlusselungsgerat-fur-mobilen-einsatz","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/compumatica-entwickelte-neues-verschlusselungsgerat-fur-mobilen-einsatz-1084\/","title":{"rendered":"Compumatica entwickelte neues Verschl\u00fcsselungsger\u00e4t f\u00fcr mobilen Einsatz"},"content":{"rendered":"<p>PRESSEMELDUNG von Compumatica secure networks<\/p> <p>Compumatica entwickelte neues Verschl\u00fcsselungsger\u00e4t f\u00fcr<br \/> mobilen Einsatz<\/p> <p>Aachen, 27. Februar 2008.- Die neueste VPN-Box von<br \/> Compumatica secure networks ist so klein, dass sie in jedes<br \/> Fahrzeug passt. Sie verschl\u00fcsselt Daten und Bilder, die aus<br \/> fahrenden Autos und Transportern gesendet werden. Das System<br \/> eignet sich f\u00fcr den Einsatz in hochsensiblen Bereichen,<!--more--><br \/> beispielsweise bei Polizei und Milit\u00e4r.<br \/> Die Verschl\u00fcsselungsbox CryptoGuard VPN 50 mobile ist eine<br \/> besonders kleine Version des CryptoGuard VPN, die sich wegen<br \/> ihrer niedrigen Bandbreite und ihres handlichen Formats<br \/> vorz\u00fcglich f\u00fcr den mobilen Einsatz in PKWs und Transportern<br \/> eignet. Auf Basis des IP-Protokolls k\u00f6nnen vertrauliche<br \/> Bilder und Daten verschl\u00fcsselt \u00fcbermittelt werden. Damit<br \/> eignet sich CryptoGuard VPN 50 mobile f\u00fcr den Schutz von<br \/> Daten in Sondertransporten, zum Beispiel im milit\u00e4rischen<br \/> und polizeilichen Bereich.<\/p> <p><script type=\"text\/javascript\"><!--\ngoogle_ad_client = \"pub-3005442858985655\";\ngoogle_ad_width = 660;\ngoogle_ad_height = 15;\ngoogle_ad_format = \"728x15_0ads_al\";\ngoogle_ad_channel = \"2589180296\";\ngoogle_color_border = \"1B446A\";\ngoogle_color_bg = \"DFE9F1\";\ngoogle_color_link = \"1B446A\";\ngoogle_color_text = \"000000\";\ngoogle_color_url = \"008000\";\n\/\/-->\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/pagead2.googlesyndication.com\/pagead\/show_ads.js\">\n<\/script><\/p> <p>CryptoGuard VPN 50 mobile wird direkt in das Fahrzeug<br \/> eingebaut und verschl\u00fcsselt Kamerabilder und andere<br \/> IP-Daten. Dabei ben\u00f6tigt das Fahrzeug keine besondere<br \/> Ausstattung, denn die Verschl\u00fcsselungsbox l\u00e4uft mit der ganz<br \/> normalen elektronischen Einrichtung eines modernen<br \/> Kraftfahrzeugs.<\/p> <p>Mit der zunehmenden elektronischen Aufr\u00fcstung von<br \/> Kraftfahrzeugen wird auch die Datenkommunikation aus dem<br \/> mobilen Einsatz heraus immer umfangreicher. Mehr und mehr<br \/> sensible IP-Daten werden direkt aus Fahrzeugen an<br \/> Ermittlungszentralen und Einsatzkr\u00e4fte geschickt. Gerade f\u00fcr<br \/> den sensiblen Bereich der Sondertransporte k\u00f6nnen die<br \/> Sicherheitskr\u00e4fte kein Risiko eingehen.<\/p> <p>Compumatica secure networks auf der CeBIT 2008 in Hannover:<br \/> Halle 6, Stand H06.<\/p>","protected":false},"excerpt":{"rendered":"<p>PRESSEMELDUNG von Compumatica secure networks Compumatica entwickelte neues Verschl\u00fcsselungsger\u00e4t f\u00fcr mobilen Einsatz Aachen, 27. Februar 2008.- Die neueste VPN-Box von Compumatica secure networks ist so klein, dass sie in jedes Fahrzeug passt. Sie verschl\u00fcsselt Daten und Bilder, die aus fahrenden Autos und Transportern gesendet werden. Das System eignet sich f\u00fcr den Einsatz in hochsensiblen Bereichen,<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,8806],"tags":[],"class_list":["post-84","post","type-post","status-publish","format-standard","hentry","category-handy-elektronik-telekommunikation","category-technik"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/84","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=84"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/84\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=84"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=84"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=84"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}