{"id":84423,"date":"2013-08-07T14:30:18","date_gmt":"2013-08-07T14:30:18","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=84423"},"modified":"2020-01-31T15:51:18","modified_gmt":"2020-01-31T14:51:18","slug":"die-digitale-speisekarte","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/die-digitale-speisekarte-1084423\/","title":{"rendered":"Die digitale Speisekarte"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"digitale Werbung direkt am Point-of-Sale\" alt=\"digitale Werbung direkt am Point-of-Sale\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/155644dde889dbf5f47e55359b21e564.jpg\" width=\"132\" height=\"132\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/7dfeaa67378f7d0f1d8e5f421de58d3d.jpg\" \/>Digitale Speisekarten und Tablets erobern die Gastronomie<\/p> <p>Screens, die zum Probieren der aktuellen Barkreation einladen, Tablets, die zum feinen Essen gleich noch das passende Getr\u00e4nk vorschlagen &#8211; Technologie h\u00e4lt Einzug in die Gastronomie. Hinter diesem Trend steht die im Juli 2013 gegr\u00fcndete Brand Views Agentur f\u00fcr digitale Medien, Hamburg.<br \/> Erfolgreich verkaufen \u00fcber Digital Signage<\/p> <p><!--more-->Brand Views stattet innovative Gastronomiebetriebe mit Hardware (Screens, Tablets) und auf den jeweiligen Betriebstyp abgestimmte Inhalte (digitale Speisekarten, Produktinszenierungen, Angebots-Platzierungen) aus. Der Vorteil f\u00fcr Restaurants, Bars, Lounges, Diskos, Clubs und Hotels, die Digital Signage in Kooperation mit Brand Views nutzen, liegt in der erfolgreichen Verkaufsf\u00f6rderung \u00fcber diese aufmerksamkeitsstarke Werbeform. Die Herausforderung f\u00fcr jeden Gastronomen besteht darin, den Bon des Gastes zu erh\u00f6hen. Brand Views und Digital Signage wirken hier mit zeitgem\u00e4\u00dfer Technologie und intelligentem Content Management weit \u00fcber das hinaus, was eine Speisekarte und das Servicepersonal bringen.<\/p> <p>Ein Markenauftritt \u00fcber Digital Signage r\u00fcckt Produkte ins Rampenlicht<\/p> <p>Die Gastronomie dient nicht nur Getr\u00e4nkeherstellern als Abverkaufs-Kanal und dar\u00fcber hinaus als Plattform f\u00fcr die Markenbildung. Auch Unternehmen anderer Branchen entdecken die Gastronomie zunehmend als emotionale B\u00fchne f\u00fcr ihre Markenkommunikation. Die werbende Industrie hat \u00fcber Digital Signage und Brand Views verschiedene M\u00f6glichkeiten, ihre Markenbotschaften zu pr\u00e4sentieren. Sollen die G\u00e4ste auf eine neue Biersorte aufmerksam gemacht werden? M\u00f6chte man ein Nischenprodukt nach vorne stellen? Gibt es interessante Sonderangebote? Screens und Tablets werden stark beachtet, die Inhalte sind flexibel zu generieren und zu schalten. Digitale Getr\u00e4nkekarten, Image-Anzeigen, Werbefilme und Aktionsangebote, bis hin zu Cross-Media-Aktionen &#8211; die Technologie er\u00f6ffnet viele Spielarten.<\/p> <p>Digital Signage &#8211; eine neue Option f\u00fcr die werbungtreibende Wirtschaft im schwierigen Absatzkanal Gastronomie<\/p> <p>Was Brand Views als Digital Signage Partner im Absatzkanal Gastronomie auszeichnet, ist die zielgruppengenaue Belegung von Gastronomie-Betriebstypen, inklusive Lage und Sortiment. So kann Werbung beispielsweise speziell nur im Channel Trend- und Szenegastronomie oder nur in klassischen Restaurants geschaltet werden. Dies ist m\u00f6glich, weil alle Brand Views Gastronomiekunden in \u00fcber 60 verschiedene Betriebstypen geclustert sind. Brand Views bringt \u00fcber Digital Signage Marken und Verbraucher ohne Streuverluste zusammen. Durch die l\u00fcckenlose Evaluierung und ein Reporting der Absatzentwicklung ist der Kampagnenerfolg in Echtzeit und f\u00fcr jedes einzelne Gastronomieobjekt messbar.<\/p> <p>Warum Digital Signage \u00fcber Brand Views funktioniert<\/p> <p>Hinter der Agentur-Neugr\u00fcndung stehen die NGV Getr\u00e4nke-Gruppe, f\u00fchrende Systemzentrale f\u00fcr den Getr\u00e4nkefachgro\u00dfhandel in Deutschland, und die A.HOII! networking unit, Experte f\u00fcr Digital Signage. Das Joint Venture ist mit \u00fcber 130 Kunden aus den Bereichen Hotellerie, Gastronomie, Gro\u00dfverbraucher, Foodservice und Catering vom Start weg einer der deutschlandweit f\u00fchrenden Digital Signage Anbieter f\u00fcr den Au\u00dfer-Haus-Markt. Gef\u00fchrt wird die Agentur von Arne Seeliger (38) und Sven Lorenzen (35). Die NGV Getr\u00e4nke-Gruppe bringt in die Zusammenarbeit den Zugang zur Industrie und die Vermarktungskompetenz im Au\u00dfer-Haus-Markt ein. Die Getr\u00e4nkefachgro\u00dfhandels-Kooperation verschafft ihren Industriepartnern mit Brand Views eine aufmerksamkeitsstarke Pr\u00e4senz im Gastraum. A.HOII! steuert das technologische Know-how bei. Als Full-Service Agentur \u00fcbernimmt A.HOII! f\u00fcr die werbenden Industriekunden die komplette Entwicklung und Umsetzung des Brand Views Auftritts. Dar\u00fcber hinaus akquiriert A.HOII! bundesweit die Gastronomiekunden.<\/p> <p>Die Basis des Erfolgs der neuen Agentur Brand Views liegt in der Branchenerfahrung im Au\u00dfer-Haus-Markt. Was leistet Brand Views und was bringt Digital Signage im Vergleich zu klassischer Werbung? Erste Antworten. (http:\/\/www.youtube.com\/watch?v=Y54fPruO7Qg#at=21)<\/p> <p>So funktioniert Digital Signage in der Gastronomie<\/p> <p>Gezielte Absatzsteigerung und eine optimale Markenkommunikation &#8211; digitale Werbung wirkt. Was sagen G\u00e4ste in Restaurants, Bars und Kneipen zur neuen Technologie? Und was sagen die Gastronomen? Erste Eindr\u00fccke. (http:\/\/www.youtube.com\/watch?v=5Yt2PLWgpA8#at=75)<\/p> <p>Bildrechte: Brand Views Agentur f\u00fcr digitale Medien<\/p> <p>Brand Views Agentur f\u00fcr digitale Medien GmbH i. Gr. (www.brandviews.de) ist ein Joint Venture der NGV Getr\u00e4nke-Gruppe (www.ngv-gruppe.de) und der A.HOII! networking unit (www.ahoii.net), alle Hamburg. Brand Views stattet den Au\u00dfer-Haus-Markt mit Screens und Tablets aus und realisiert auf das jeweilige Objekt ma\u00dfgeschneiderten Content. Die Zielsetzung liegt im Abverkauf und in der Generierung von Transparenz im Au\u00dfer-Haus-Verkaufskanal, um einerseits die Industrie in ihren Vertriebsbem\u00fchungen zu unterst\u00fctzen und andererseits Gastronomen in ihrer optimalen Sortimentsgestaltung zu beraten. F\u00fcr die werbungtreibende Wirtschaft stellt Brand Views damit eine einzigartige Plattform zur direkten, effizienten und zeitgem\u00e4\u00dfen Ansprache ihrer Zielgruppen bereit, zum Nutzen aller Beteiligten.<\/p> <p>Kontakt<br \/> Brand Views Agentur f\u00fcr digitale Medien<br \/> Arne Seeliger und Sven Lorenzen<br \/> Barnerstra\u00dfe 1<br \/> 22765 Hamburg<br \/> 040 48 40 455-51<br \/> info@brandviews.de<br \/> http:\/\/www.brandviews.de<\/p> <p>Pressekontakt:<br \/> NGV Unternehmens:kommunikation<br \/> Ann-Christin Zilling<br \/> Breckwoldtstra\u00dfe 6<br \/> 22587 Hamburg<br \/> 04084058664<br \/> ac.zilling@hamburg.de<br \/> http:\/\/www.ann-christin-zilling.de<\/p> <p>&nbsp;<\/p> <p>URL zum YouTube-Video: <object width=\"425\" height=\"344\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowfullscreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/5Yt2PLWgpA8&amp;hl=en&amp;fs=1\" \/><embed width=\"425\" height=\"344\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.youtube.com\/v\/5Yt2PLWgpA8&amp;hl=en&amp;fs=1\" allowfullscreen=\"true\" allowscriptaccess=\"always\" \/><\/object><\/p>","protected":false},"excerpt":{"rendered":"<p>Digitale Speisekarten und Tablets erobern die Gastronomie Screens, die zum Probieren der aktuellen Barkreation einladen, Tablets, die zum feinen Essen gleich noch das passende Getr\u00e4nk vorschlagen &#8211; Technologie h\u00e4lt Einzug in die Gastronomie. Hinter diesem Trend steht die im Juli 2013 gegr\u00fcndete Brand Views Agentur f\u00fcr digitale Medien, Hamburg. Erfolgreich verkaufen \u00fcber Digital Signage<\/p>\n","protected":false},"author":3,"featured_media":197037,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[1734],"class_list":["post-84423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business-handel-gewerbe","tag-default"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/84423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=84423"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/84423\/revisions"}],"predecessor-version":[{"id":271366,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/84423\/revisions\/271366"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/197037"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=84423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=84423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=84423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}