{"id":85873,"date":"2013-08-16T12:04:58","date_gmt":"2013-08-16T11:04:58","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=85873"},"modified":"2018-09-13T09:26:30","modified_gmt":"2018-09-13T08:26:30","slug":"die-innovation-fuer-maennerhaare","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/die-innovation-fuer-maennerhaare-1085873\/","title":{"rendered":"Die Innovation f\u00fcr M\u00e4nnerhaare"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-85874\" title=\"60 Prozent aller M\u00e4nner leiden im Laufe ihres Lebens unter Haar\u00adausfall. Haar\u00add\u00fcnger kann den Haar\u00adausfall bereits nach 6 - 12 Wochen stoppen. \" alt=\"60 Prozent aller M\u00e4nner leiden im Laufe ihres Lebens unter Haar\u00adausfall. Haar\u00add\u00fcnger kann den Haar\u00adausfall bereits nach 6 - 12 Wochen stoppen. \" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/a657e4e4bdcdc15c4c7d945b46edfa2d.jpg\" width=\"191\" height=\"163\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/a823a1723d34473667d510eef4a72399.jpg\" \/>In der Schweiz gegen erblich bedingten Haarausfall entwickelt, in Deutschland produziert, sorgt Haard\u00fcnger bei jungen M\u00e4nnern f\u00fcr berechtigte Hoffnung&#8230;<\/p> <p>T\u00e4gerwilen, den 15. August 2013. M\u00e4nner mit ersten Anzeichen von Haarausfall k\u00f6nnen wieder hoffen. Nach intensiver Forschung ist der Durchbruch im Bereich des erblich bedingten Haarausfalls gelungen. Schweizer Grundlagenforscher pr\u00e4sentierten hierzulande die Innovation des Jahres den Haard\u00fcnger. Damit ist das von der Bonafair AG vertriebene Haarprodukt endlich auch in Deutschland angekommen. Mit seinem neuartigen Wirkstoffkomplex, den bioaktiven Sterolen, sorgt es f\u00fcr reichlich Wirbel auf dem Markt. \u00dcber einen eigenen Onlineshop und autorisierte Friseure vertrieben, unterscheidet sich Haard\u00fcnger deutlich von Wunder versprechenden Konkurrenten.<\/p> <p><!--more-->Wir dopen keine Haare. Wir lassen auch keine neuen Haarwurzeln wundersam sprie\u00dfen. Haard\u00fcnger sch\u00fctzt die Haarfollikel von M\u00e4nnern. Er verhindert bzw. verringert erblich bedingten Haarausfall, bevor permanente Sch\u00e4den entstehen, so Lothar Hartinger, Verwaltungsratspr\u00e4sident der Bonafair AG. Unser Ziel war die Marktreife eines wirksamen Haarwuchsproduktes. Eine Schweizer Forschungsgruppe entwickelte die wissenschaftlichen Grundlagen. Mittlerweile arbeiten wir intensiv und grenz\u00fcberschreitend zusammen. Haard\u00fcnger wird unter strengen Qualit\u00e4tsstandards in Deutschland produziert, erkl\u00e4rt Lothar Hartinger.<\/p> <p>Die Ursache von erblich bedingtem Haarausfall, ein Ungleichgewicht m\u00e4nnlicher und weiblicher Botenstoffe, wird durch Haard\u00fcnger in den Haarwurzeln ausgeglichen. Die bioaktiven Sterole normalisieren die Wachstumsphase der Haare. Der fr\u00fchzeitige Eintritt der Haarfollikel in die Ruhephase wird so verhindert. Vor dem Verkaufstart in Deutschland wurde nat\u00fcrlich auch hierzulande intensiv getestet und nachgefragt. Die Erfolge der Schweizer Markteinf\u00fchrung waren schlie\u00dflich das ausgemachte Ziel. Die erste Zwischenbilanz ist durchweg positiv. Immer mehr Bestellungen kommen t\u00e4glich an.<\/p> <p>Haard\u00fcnger setzt damit seinen Erfolgszug weiter fort. Entsprechend zufrieden ist das Haard\u00fcnger-Team der Bonafair AG.<\/p> <p>Firmenkontakt<br \/> Bonafair AG<br \/> Julia Domschke<br \/> Kontanzerstra\u00dfe 19<\/p> <p>8274 T\u00e4gerwilen<br \/> &#8211;<\/p> <p>E-Mail: presse@haarduenger.de<br \/> Homepage: http:\/\/www.haarduenger.de<br \/> Telefon: 0041 71511 4991<\/p> <p>Pressekontakt<br \/> Bonafair AG<br \/> Julia Domschke<br \/> Kontanzerstra\u00dfe 19<\/p> <p>8274 T\u00e4gerwilen<br \/> &#8211;<\/p> <p>E-Mail: presse@haarduenger.de<br \/> Homepage: http:\/\/<br \/> Telefon: 0041 71511 4991<\/p>","protected":false},"excerpt":{"rendered":"<p>In der Schweiz gegen erblich bedingten Haarausfall entwickelt, in Deutschland produziert, sorgt Haard\u00fcnger bei jungen M\u00e4nnern f\u00fcr berechtigte Hoffnung&#8230; T\u00e4gerwilen, den 15. August 2013. M\u00e4nner mit ersten Anzeichen von Haarausfall k\u00f6nnen wieder hoffen. Nach intensiver Forschung ist der Durchbruch im Bereich des erblich bedingten Haarausfalls gelungen. Schweizer Grundlagenforscher pr\u00e4sentierten hierzulande die Innovation des Jahres den<\/p>\n","protected":false},"author":3,"featured_media":85874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8805],"tags":[],"class_list":["post-85873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shopping"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/85873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=85873"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/85873\/revisions"}],"predecessor-version":[{"id":270123,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/85873\/revisions\/270123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/85874"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=85873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=85873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=85873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}