{"id":88,"date":"2008-03-01T17:15:43","date_gmt":"2008-03-01T16:15:43","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/vom-manuskript-zum-buch-%e2%80%93-kostenlos\/"},"modified":"2010-07-28T10:13:20","modified_gmt":"2010-07-28T09:13:20","slug":"vom-manuskript-zum-buch-kostenlos","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/vom-manuskript-zum-buch-kostenlos-1088\/","title":{"rendered":"Vom Manuskript zum Buch \u2013 kostenlos!"},"content":{"rendered":"<p>Dass sog. Druckkosten-Zuschuss-Verlage eine bisweilen horrende finanzielle Eigenbeteiligung des Autoren bzw. der Autorin verlangen, ist weitestgehend bekannt. Dennoch investieren Autoren und -Innen in ein solches Unternehmen.<br \/> Unglaublich \u2013 aber Tatsache. Statt sich eingehender zu informieren, wird das erstbeste Angebot angenommen, akzeptiert und \u2013 bezahlt! Hauptsache, man hat &#8222;sein&#8220; Buch in der Hand. Doch zu welchem Preis?!<!--more--><br \/> Oftmals machen solcherart DZ-Verlage zur Auflage, eine gewisse St\u00fcckzahl selber abzunehmen (f\u00fcr Freunde, Verwandte und Bekannte, etc.), die zwar verbilligt vom Verlag erh\u00e4ltlich sind, was aber nichts daran \u00e4ndert, auch f\u00fcr diese nochmal in die Tasche greifen zu m\u00fcssen, wogegen der VERkauf allerdings zumeist auf der Strecke bleibt. Zudem: Freunden will man sein Buch ja auch nicht verkaufen, die kriegen es nat\u00fcrlich geschenkt. Ist ja auch gut so und richtig. Nur \u2013 so ein kleines Bisschen Gewinn m\u00f6chte man (frau) im Grunde ja vielleicht doch &#8230;? Die Frage ist nur das WIE?!<br \/> Und genau diese Frage m\u00f6chten wir Ihnen beantworten. Gerne und \u2013 kostenlos!<br \/> Wenn Sie also \u00fcber ein Skript verf\u00fcgen, mit dem Sie vielleicht bisher vergeblich an manche Verlagst\u00fcr angeklopft haben und abgewiesen wurden, nehmen Sie bitte ganz unverbindlich Kontakt mit uns auf. Am besten per e-mail:<\/p> <p><script type=\"text\/javascript\">\/\/ <![CDATA[\ngoogle_ad_client = \"pub-3005442858985655\";\ngoogle_ad_width = 660;\ngoogle_ad_height = 15;\ngoogle_ad_format = \"728x15_0ads_al\";\ngoogle_ad_channel = \"2589180296\";\ngoogle_color_border = \"1B446A\";\ngoogle_color_bg = \"DFE9F1\";\ngoogle_color_link = \"1B446A\";\ngoogle_color_text = \"000000\";\ngoogle_color_url = \"008000\";\n\/\/ ]]><\/script><script src=\"http:\/\/pagead2.googlesyndication.com\/pagead\/show_ads.js\" type=\"text\/javascript\">\n<\/script><\/p> <p>j-d-i-gerd-kirvel@gmx.de<br \/> Besuchen Sie gern zur Vorabinformation unsere HP: www.Jenseits-des-Irdischen.de<br \/> Unter der Menue-Rubrik &#8222;Buchtipp&#8220; finden Sie einige Titel von Autoren, denen wir haben helfen k\u00f6nnen und die heute ebenfalls &#8222;stolze Besitzer eines eigenen Buches&#8220; sind \u2013 ohne Druckkostenzuschuss.<br \/> In diesem Sinne und danke f\u00fcr Ihre Aufmerksamkeit<\/p>","protected":false},"excerpt":{"rendered":"<p>Dass sog. Druckkosten-Zuschuss-Verlage eine bisweilen horrende finanzielle Eigenbeteiligung des Autoren bzw. der Autorin verlangen, ist weitestgehend bekannt. Dennoch investieren Autoren und -Innen in ein solches Unternehmen. Unglaublich \u2013 aber Tatsache. Statt sich eingehender zu informieren, wird das erstbeste Angebot angenommen, akzeptiert und \u2013 bezahlt! Hauptsache, man hat &#8222;sein&#8220; Buch in der Hand. Doch zu welchem<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[232,231,229,230,228,234,236,233,235],"class_list":["post-88","post","type-post","status-publish","format-standard","hentry","category-journalismus-medien-publizistik","tag-autor-sucht-verlag","tag-buch-zum-nulltarif","tag-buchdruck","tag-eigenes-buch","tag-manuskript","tag-mein-buch","tag-ohne-kosten-zum-eigenen-buch","tag-verlag-sucht-autor","tag-will-buch-drucken-lassen"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/88","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=88"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/88\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=88"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=88"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=88"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}