{"id":89437,"date":"2013-09-02T10:15:32","date_gmt":"2013-09-02T10:15:32","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=89437"},"modified":"2018-08-03T11:21:39","modified_gmt":"2018-08-03T10:21:39","slug":"wiese-ist-nicht-gleich-wiese","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wiese-ist-nicht-gleich-wiese-1089437\/","title":{"rendered":"Wiese ist nicht gleich Wiese"},"content":{"rendered":"<p>Multimedialer Erlebnisraum Schaf und Natur in Hungen er\u00f6ffnet<\/p> <p>Im neu er\u00f6ffneten &#8222;Erlebnisraum Schaf und Natur &#8211; unterwegs in den Wetterauer Hutungen&#8220; kann man die Artenvielfalt und die Bedeutung der Sch\u00e4ferei f\u00fcr diese tradtionellen Weidefl\u00e4chen mit allen Sinnen entdecken,<br \/> Im &#8222;Erlebnisraum Schaf und Natur &#8211; unterwegs in den Wetterauer Hutungen&#8220;, der auf Initiative der Stadt Hungen und als Ma\u00dfnahme des LIFE-Projekt &#8222;Wetterauer Hutungen&#8220; entstanden ist, wird das umweltrelevante Thema zum Erhalt dieser traditionellen und artenreichen Weidefl\u00e4chen im s\u00fcdlichen Landkreis Gie\u00dfen und im n\u00f6rdlichen Wetteraukreis p\u00e4dagogisch wertvoll, multimedial und sinnlich erlebbar aufbereitet.<\/p> <p><!--more-->Heide ist nicht nur ein Vorname, Magerrasen sind reich an zahlreichen selten gewordenen Tieren und Pflanzen. Wiese ist nicht gleich Wiese und Steine leben doch. Im neu geschaffenen, multimedialen Erlebnisraum im Obergeschoss der Hungener K\u00e4sescheune kann man auf 65 Quadratmetern die artenreiche Tier- und Pflanzenwelt der Wetterauer Hutungen kennenlernen. Der &#8222;Erlebnisraum Schaf und Natur&#8220; bietet viele interessante und spannende Einblicke in das Life-Projekt &#8222;Wetterauer Hutungen&#8220; und h\u00e4lt reichlich Informationen zu Themen wie Sch\u00e4ferei fr\u00fcher und heute, Schafe als Nutztiere, Hungen als Sch\u00e4ferstadt sowie die Bedeutung des ehrenamtlichen Naturschutzes bereit. B\u00fcrgermeister Rainer Wengorsch ist sehr erfreut, dass Hungen als Sch\u00e4ferstadt ein Informationszentrum zum Thema Schaf und Natur B\u00fcrgerinnen und B\u00fcrgern sowie Besuchern der Stadt Hungen als eine weitere touristische Sehensw\u00fcrdigkeit pr\u00e4sentieren kann. &#8222;Der Erlebnisraum Schaf und Natur bringt den Menschen den regionalen Erlebnisraum n\u00e4her und ist eine Bereicherung f\u00fcr das Freizeitangebot im Landkreis Gie\u00dfen&#8220;, sagt Wengorsch.<\/p> <p>Die Dauerausstellung will informieren und unterhalten, deshalb ist Vielfalt Trumpf. Das Raumkonzept erlaubt es, begleitet von den &#8222;Helden&#8220; der Ausstellung &#8211; den Schafe &#8211; den Erlebnisraum zu erkunden. Denn es gibt zahlreiche Stationen und Angebote, ob reine Sachinformationen oder spielerische Erlebnisstationen. Zwei &#8222;Highlights&#8220; werden sicherlich einen nachhaltigen Eindruck hinterlassen: In der Filmecke wird mit einem Augenzwinkern die Welt des Sch\u00e4fers im Originalma\u00dfstab inszeniert. Ein f\u00fcr den Erlebnisraum produzierter Film zeigt dort in verschiedenen Kapiteln die Arbeit des Sch\u00e4fers und die Anstrengungen im Naturschutz auf den Hutefl\u00e4chen in all ihren Facetten.<\/p> <p>Die Hauptvitrine fasziniert mit ihren Pflanzen- und Tierpr\u00e4paraten und macht den Reichtum der Magerrasenfl\u00e4chen durch beeindruckende Details deutlich. Interaktive Stationen mit aktueller Medientechnik bieten einen leichten und verst\u00e4ndlichen \u00dcberblick \u00fcber das Ausstellungsthema, zeigen alte und neue Fotos in Gegen\u00fcberstellung. Mitmachstationen laden zu einem kleinen Quiz, das eigene Wissen zu testen ein. Das Landschaftsmodell des Villinger Wallenbergs im Ma\u00dfstab 1:87 d\u00fcrfte nicht nur die Modellbau-Fans begeistern. Hier wird anschaulich, welchen Ver\u00e4nderungen die alten Hutungen unterworfen waren und welche Anstrengungen unternommen werden m\u00fcssen, um die Artenvielfalt dieser einzigartigen Biotope zu erhalten. Neben vielen Informationen gibt es aber auch M\u00f6glichkeiten, sich spielerisch den verschiedenen Themenbereichen zu n\u00e4hern. So k\u00f6nnen unterschiedliche Fell- bzw. Wollqualit\u00e4ten gef\u00fchlt und die imposanten Geh\u00f6rne verschiedener Schafrassen bestaunt werden. In klassischen &#8222;Museums-Schubladen&#8220; gibt es einiges zu entdecken. Das alles und noch viel mehr kann man im &#8222;Erlebnisraum Schaf und Natur&#8220;, mit allen Sinnen erfahren und im besten Sinne des Wortes begreifen. Denn Anfassen ist ausdr\u00fccklich erw\u00fcnscht! F\u00fcr wissenschaftlich Interessierten steht eine kleine Fachbibliothek bereit. Wer weiterf\u00fchrende Recherchen zu den Themen der Ausstellung machen will, ist in am PC-Platz mit seiner Datenbank bestens aufgehoben. &#8222;Der Erlebnisraum soll den Menschen die Artenvielfalt auf den Wetterauer Hutungen vor der Haust\u00fcr und die Bedeutung der Nutzung dieser Fl\u00e4chen durch traditionelle Weidetiere wie Schafe und der Sch\u00e4ferei als Mitgestalter der Landschaft n\u00e4her bringen&#8220;, sagt Life-Projektleiterin Jutta Katz.<\/p> <p>Insgesamt wurden f\u00fcr die Planung und Gestaltung des Erlebnisraumes 130.000 Euro investiert. Projekttr\u00e4ger ist das Hessische Ministerium f\u00fcr Umwelt, Energie und Landwirtschaft (HMUELV), Projektpartner ist die Stadt Hungen. Die Finanzierung erfolgt zu 100 Prozent \u00fcber Mittel des EU-F\u00f6rderprogramm Life .<\/p> <p>F\u00fchrungen durch den &#8222;Erlebnisraum Schaf und Natur &#8211; unterwegs in den Wetterauer Hutungen&#8220; k\u00f6nnen unter 06402\/518857-2 (Hungener K\u00e4sescheune) und 06402\/85-0 (Stadt Hungen) vereinbart werden. Man kann den Erlebnisraum jedoch auch sehr gut auf eigene Faust erkunden und erleben. \u00d6ffnungszeiten: Di-Sa 9-22 Uhr, So 11-22 Uhr.<\/p> <p>Bildrechte: Marion L\u00f6hr-B\u00f6ger<\/p> <p>Beh\u00f6rde, Naturschutz<\/p> <p>Kontakt<br \/> Life-Projekt Wetterauer Hutungen<br \/> Jutta Katz<br \/> Mainzer Stra\u00dfe 80<br \/> 65189 Wiesbaden<br \/> 0641\/4991-253<br \/> Jutta.Katz@forst.hessen.de<br \/> http:\/\/www.wetterauer-hutungen.de<\/p> <p>Pressekontakt:<br \/> Ingrid Schick Kommunikation<br \/> Ingrid Schick<br \/> Solmser Weg 16<br \/> 61184 Karben<br \/> 06039 41831<br \/> kontakt@ingrid-schick-kommunikationde.de<br \/> http:\/\/www.ingrid-schick-kommunikation.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Multimedialer Erlebnisraum Schaf und Natur in Hungen er\u00f6ffnet Im neu er\u00f6ffneten &#8222;Erlebnisraum Schaf und Natur &#8211; unterwegs in den Wetterauer Hutungen&#8220; kann man die Artenvielfalt und die Bedeutung der Sch\u00e4ferei f\u00fcr diese tradtionellen Weidefl\u00e4chen mit allen Sinnen entdecken, Im &#8222;Erlebnisraum Schaf und Natur &#8211; unterwegs in den Wetterauer Hutungen&#8220;, der auf Initiative der Stadt Hungen<\/p>\n","protected":false},"author":3,"featured_media":89438,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[1734],"class_list":["post-89437","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ernahrung-umwelt-natur","tag-default"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/89437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=89437"}],"version-history":[{"count":2,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/89437\/revisions"}],"predecessor-version":[{"id":270023,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/89437\/revisions\/270023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/89438"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=89437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=89437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=89437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}