{"id":90059,"date":"2013-09-04T07:45:05","date_gmt":"2013-09-04T07:45:05","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=90059"},"modified":"2013-09-04T17:17:57","modified_gmt":"2013-09-04T16:17:57","slug":"die-maennliche-scheidung","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/die-maennliche-scheidung-1090059\/","title":{"rendered":"Die m\u00e4nnliche Scheidung"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Scheidungsberater f\u00fcr M\u00e4nner\" alt=\"Scheidungsberater f\u00fcr M\u00e4nner\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/a3733e1e5a74740fb048bb32aff6fde9.jpg\" width=\"128\" height=\"128\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/1691d9c0e9e9f27d7ae19ab3aaea9501.jpg\" \/>Der Feind im Bett<\/p> <p>Vor dem Gesetz sind alle gleich? Dieser Satz ist sicherlich vielen gel\u00e4ufig. Und doch fragt man sich gelegentlich, ob manche &#8222;gleicher als andere sind&#8220;? Gunter Schlickum, Rechtsanwalt und Mediator in M\u00fcnchen mit langj\u00e4hriger Erfahrung im Familienrecht, stellt in seinem Ratgeber &#8222;Scheidungsberater f\u00fcr M\u00e4nner&#8220; aus der Reihe Beck Rechtsberater im dtv (Verlag C.H.BECK) f\u00fcr jederMann leichtverst\u00e4ndlich das Strickmuster vor, nach dem die Scheidungsmasche l\u00e4uft.<\/p> <p><!--more-->Ehemann vs. Ehefrau. Es gibt nur ein Recht, aber unterschiedliche rechtliche Blickwinkel. Das gilt f\u00fcr kein Rechtsgebiet so sehr wie f\u00fcr das Familienrecht. &#8222;Oft wird der Mann am Ende einer Lebensgemeinschaft zur Kasse gebeten. Daher sollten sich M\u00e4nner bereits im Vorfeld umfassend \u00fcber die wesentlichen Aspekte, die bei Trennung und Scheidung zu beachten sind, informieren&#8220;, empfiehlt Familienrechts-Experte Gunter Schlickum, denn &#8222;einen ewig andauernden Rosenkrieg will niemand.&#8220; Das hei\u00dft im Klartext: Rechtzeitig die Weichen stellen und geschickt handeln.<\/p> <p>Fragen \u00fcber Fragen. Muss ich Unterhalt f\u00fcr meine Ex-Frau zahlen? Wenn ja, wieviel? Und wie lange? &#8222;Der Ehegattenunterhalt ist die am meisten umk\u00e4mpfte Scheidungsfolge&#8220;, res\u00fcmiert der Experte. &#8222;Wenn zum Beispiel Ihre Ex zun\u00e4chst keinen Unterhalt verlangt und es sich sp\u00e4ter anders \u00fcberlegt, brauchen Sie nicht zu bef\u00fcrchten, f\u00fcr die inzwischen verstrichene Zeit in Anspruch genommen zu werden. Es sei denn, Ihre Frau hat den Unterhalt in einer bestimmten H\u00f6he angemahnt oder Sie aufgefordert, Auskunft \u00fcber Ihr Einkommen zu geben&#8220;, kl\u00e4rt Schlickum auf. Bescheid wissen lohnt sich also.<\/p> <p>Verliebt, verlobt, geschieden. Die wenigsten M\u00e4nner sind sich bei der Eheschlie\u00dfung dar\u00fcber bewusst, dass Sie auch den Staat als Vertragspartner mit ins Bett nehmen. Doch eine Trennung hat erhebliche rechtliche Konsequenzen. &#8222;Einige Rechtsfolgen treten ohne weiteres Zutun ein, andere k\u00f6nnen auf Antrag herbeigef\u00fchrt werden&#8220;, so Gunter Schlickum. Mann sollte folglich \u00fcber die relevanten rechtlichen Konsequenzen informiert sein. &#8222;Ehewohnung und Hausrat, Scheidungsverfahren und Kosten, Ehegatten- und Kindesunterhalt sowie das besonders heikle Thema des Sorge- und Umgangsrechts sind Punkte auf der Scheidungsliste, die jeder Mann nicht ohne Weiteres einfach abhaken sollte&#8220;, r\u00e4t der Rechtsanwalt.<\/p> <p>Beck Rechtsratgeber im dtv<br \/> Gunter Schlickum, Scheidungsberater f\u00fcr M\u00e4nner, Verlag C.H.BECK, 3. Auflage, 2013, XIII, 177 Seiten, kartoniert EUR 12,90, ISBN 978-3-406-64839-7, <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.beck-shop.de\/11730261\" title=\"die Fachbuchhandlung\" >www.beck-shop.de\/11730261<\/a>.<br \/> Das Werk ist auch als eBook erh\u00e4ltlich.<\/p> <p>Der Verlag C.H.BECK z\u00e4hlt zu den gro\u00dfen Verlagen in Deutschland. Daf\u00fcr sprechen \u00fcber 9.000 lieferbare Werke, rund 70 Fachzeitschriften sowie j\u00e4hrlich bis zu 1.500 Neuerscheinungen und Neuauflagen. Unter ihnen befinden sich renommierte juristische B\u00fccher wie Sch\u00f6nfelder &#8222;Deutsche Gesetze&#8220;, Palandt &#8222;B\u00fcrgerliches Gesetzbuch&#8220; sowie die &#8222;Neue Juristische Wochenschrift&#8220;, aber auch zahlreiche praktische Ratgeber f\u00fcr Verbraucher. Viele der Werke sind zusammen mit umfangreicher Rechtsprechung und mehr als 4.500 Gesetzen digital \u00fcber beck-online (www.beck-online.de), die mehrfach ausgezeichnete juristische Datenbank des Verlages, abrufbar. Im Web 2.0 ist C.H.Beck unter anderem mit dem beck-blog (www.beck-blog.de) und auf Facebook aktiv. In diesem Jahr feiert C.H.BECK sein 250-j\u00e4hriges Bestehen.<\/p> <p>Kontakt<br \/> Verlage C.H.BECK oHG<br \/> Mathias Bruchmann<br \/> Wilhelmstra\u00dfe 9<br \/> 80801 M\u00fcnchen<br \/> 089\/38189-266<br \/> Mathias.Bruchmann@beck.de<br \/> http:\/\/www.presse.beck.de<\/p> <p>Pressekontakt:<br \/> Verlage C.H.BECK oHG \/ Franz Vahlen GmbH<br \/> Katharina Schulz<br \/> Wilhelmstra\u00dfe 9<br \/> 80801 M\u00fcnchen<br \/> 089\/38189-666<br \/> Katharina.Schulz@beck.de<br \/> http:\/\/www.presse.beck.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Der Feind im Bett Vor dem Gesetz sind alle gleich? Dieser Satz ist sicherlich vielen gel\u00e4ufig. Und doch fragt man sich gelegentlich, ob manche &#8222;gleicher als andere sind&#8220;? Gunter Schlickum, Rechtsanwalt und Mediator in M\u00fcnchen mit langj\u00e4hriger Erfahrung im Familienrecht, stellt in seinem Ratgeber &#8222;Scheidungsberater f\u00fcr M\u00e4nner&#8220; aus der Reihe Beck Rechtsberater im dtv (Verlag<\/p>\n","protected":false},"author":3,"featured_media":196976,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[1734],"class_list":["post-90059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recht-wirtschaft-steuerberatung","tag-default"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/90059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=90059"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/90059\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/196976"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=90059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=90059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=90059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}