{"id":91934,"date":"2013-09-12T14:11:59","date_gmt":"2013-09-12T13:11:59","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=91934"},"modified":"2013-09-12T14:11:59","modified_gmt":"2013-09-12T13:11:59","slug":"coolshirt-die-therapie-bei-schulterschmerzen-und-schleimbeutelentzuendungen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/coolshirt-die-therapie-bei-schulterschmerzen-und-schleimbeutelentzuendungen-1091934\/","title":{"rendered":"Coolshirt &#8211; Die Therapie bei Schulterschmerzen und Schleimbeutelentz\u00fcndungen"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-91935\" title=\"Entz\u00fcndungen bek\u00e4mpfen durch K\u00fchlung\" alt=\"Entz\u00fcndungen bek\u00e4mpfen durch K\u00fchlung\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/746c97e24368930bc613b566072d9ddb.jpg\" width=\"188\" height=\"124\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/697fa0ccbf7f16197dc0f29cc7a01a94.jpg\" \/>Entz\u00fcndungen des Schleimbeutels (Bursitis), der Schulterdach- sowie der Bizepssehne werden viel zu oft und viel zu fr\u00fch mit Medikamenten oder sogar mit Kortison behandelt. Das innovative CoolShirt der AktiFlex-Schulterexperten k\u00f6nnte das demn\u00e4chst \u00e4ndern.<\/p> <p>K\u00fchlung ist bei vielen Entz\u00fcndungen eine wirksame, schmerzlindernde und schonende Therapie. Bei Entz\u00fcndungen im Schulterbereich gestaltet sich die K\u00fchlung allerdings sehr umst\u00e4ndlich, insbesondere, wenn man dabei weiterhin seinen Aktivit\u00e4ten nachgehen m\u00f6chte. Mit einer einfachen, aber effizienten Idee hat Thomas Duttine, Gesch\u00e4ftsf\u00fchrer und Inhaber der Aktiflex KG sein Sortiment f\u00fcr Schultergeplagte erweitert. <!--more-->Der Erfinder des Aktiflex Schulter-Trainers hat ein sogenanntes CoolShirt entwickelt, ein T-Shirt, dessen aufgesetzte Taschen exakt im Bereich der Schleimbeutel und oberen Sehne der Schulter (Supraspinatussehne), sowie an der Stelle der &#8211; meist auch entz\u00fcndeten &#8211; Bizepssehne angebracht sind. In diese Taschen k\u00f6nnen besonders kleine Eis-Gel-Packs gesteckt werden, die nur dieses Areal ganz gezielt k\u00fchlen. Dadurch entsteht keine schmerzhafte und unn\u00f6tige Unterk\u00fchlung umliegender Muskel- und Gewebebereiche. Der Stoff des cleveren, in allen Gr\u00f6\u00dfen erh\u00e4ltlichen CoolShirts verhindert automatisch den direkten Hautkontakt zum Eis-Pack.<\/p> <p>Ohne Medikamente zum Erfolg<\/p> <p>Die h\u00e4ufigen, aber kurzen K\u00fchlintervalle (zehnmal oder h\u00e4ufiger pro Tag, jeweils maximal f\u00fcr f\u00fcnf bis zehn Minuten) bek\u00e4mpfen Ursache und Symptom gleichzeitig. Die kleinfl\u00e4chige K\u00fchlung lindert den Schmerz und d\u00e4mpft die Entz\u00fcndungsreaktion. Sobald sich das Gewebe wieder erw\u00e4rmt, wird es st\u00e4rker durchblutet. Dieser Wechsel aus schonender K\u00fchlung und Erw\u00e4rmung mobilisiert die k\u00f6rpereigenen Mechanismen der Entz\u00fcndungsbehandlung. Schon nach zwei bis drei Tagen tritt im Allgemeinen eine Verbesserung ein.<\/p> <p>&#8222;Das CoolShirt ist eine perfekte Erg\u00e4nzung des AktiFlex-SchulterTrainers, welcher auch unter dem Namen Schulterhorn und Schulterhilfe bekannt ist&#8220;, sagt der Schulterexperte Thomas Duttine. &#8222;Der Schultertrainer hat bereits vielen Patienten, die unter mit Schulterschmerzen leiden, eine Operation erspart.&#8220; Durch die konsequente K\u00fchlung in Kombination mit dem Schultertrainer lassen sich Schulterprobleme nachhaltig bek\u00e4mpfen. Schmerzmittel, die h\u00e4ufig in Verbindung mit Magenschonern geschluckt werden, m\u00fcssen seltener eingenommen werden. Das hilft nicht nur dem Magen, sondern steigert insgesamt die Lebensqualit\u00e4t. Das CoolShirt ist ab 16,90 EUR inkl. MwSt. bei AktiFlex erh\u00e4ltlich.<\/p> <p>Firmenkontakt<br \/> AktiFlex-Produkte KG<br \/> Thomas Duttine<br \/> Industriestra\u00dfe 34<\/p> <p>63150 Heusenstamm<br \/> Deutschland<\/p> <p>E-Mail: Info@schulterhilfe.de<br \/> Homepage: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.schulter24.de\" title=\"Schulterschmerzen - Hilfe und Informationen\" >http:\/\/www.schulter24.de<\/a><br \/> Telefon: 06104 \/ 953 1234<\/p> <p>Pressekontakt<br \/> AktiFlex-Produkte KG<br \/> Thomas Duttine<br \/> Industriestra\u00dfe 34<\/p> <p>63150 Heusenstamm<br \/> Deutschland<\/p> <p>E-Mail: Info@schulterhilfe.de<br \/> Homepage: http:\/\/www.schulter24.de<br \/> Telefon: 06104 \/ 953 1234<\/p>","protected":false},"excerpt":{"rendered":"<p>Entz\u00fcndungen des Schleimbeutels (Bursitis), der Schulterdach- sowie der Bizepssehne werden viel zu oft und viel zu fr\u00fch mit Medikamenten oder sogar mit Kortison behandelt. Das innovative CoolShirt der AktiFlex-Schulterexperten k\u00f6nnte das demn\u00e4chst \u00e4ndern. K\u00fchlung ist bei vielen Entz\u00fcndungen eine wirksame, schmerzlindernde und schonende Therapie. Bei Entz\u00fcndungen im Schulterbereich gestaltet sich die K\u00fchlung allerdings sehr umst\u00e4ndlich,<\/p>\n","protected":false},"author":3,"featured_media":91935,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-91934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medizin-gesundheit-pflege-soziales"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/91934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=91934"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/91934\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/91935"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=91934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=91934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=91934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}