{"id":931,"date":"2009-04-06T18:34:17","date_gmt":"2009-04-06T17:34:17","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/keine-mauerblumchen-im-buro-10931\/"},"modified":"2020-03-06T11:14:17","modified_gmt":"2020-03-06T10:14:17","slug":"keine-mauerblumchen-im-buro","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/keine-mauerblumchen-im-buro-10931\/","title":{"rendered":"Keine Mauerbl\u00fcmchen im B\u00fcro"},"content":{"rendered":"<p>Trends, Chancen und Weiterbildung rund um den Arbeitsplatz B\u00fcro bei der career@office 2009<\/p> <p>Wiesbaden\/Frankfurt, 01. April 2009. Telefonate f\u00fchren, Briefe schreiben und Kaffee kochen war gestern. Aus der Sekret\u00e4rin ist die Office-Managerin geworden, denn das Berufsbild hat sich radikal ver\u00e4ndert. Wer heute erfolgreich im B\u00fcro arbeiten m\u00f6chte, muss Managementqualit\u00e4ten beweisen. Die diesj\u00e4hrige career@office \u2013 die gemeinsame Karriere-Messe von SEKRETARIAT SEMINARE und der Fachzeitschrift working@office aus dem Wiesbadener Gabler Verlag \u2013 zeigt wie Assistentinnen erfolgreich ihre Frau stehen. Die Veranstaltung findet am 15. Mai 2009 von 09.00 \u2013 17.30 Uhr in den R\u00e4umen der Industrie- und Handelskammer in Frankfurt am Main statt.<!--more--><\/p> <p>&#8222;Mein Arbeitsalltag h\u00e4ngt von dem Funktionieren meines B\u00fcros ab.&#8220; ist sich Petra Roth, Oberb\u00fcrgermeisterin der Stadt Frankfurt und Schirmherrin der career@office, sicher. Denn ihr Team organisiert und koordiniert nicht nur ihre Termine, sondern beweist oft diplomatisches Geschick, wenn es um wichtige Telefonate oder schwierige Gesch\u00e4ftskontakte geht. Fachkompetenz allein reicht deshalb schon lange nicht mehr aus. Das richtige Auftreten ist ein Karrieremotor und deshalb er\u00f6ffnet die diesj\u00e4hrige career@office mit dem Vortrag &#8222;Vom Mauerbl\u00fcmchen zur Orchidee.&#8220; Ab 09.30 Uhr erfahren die Teilnehmerinnen, wie sie ihren beruflichen Erfolg ausstrahlen und genie\u00dfen k\u00f6nnen. Weitere Schwerpunkte sind Gelassenheit und Schlagfertigkeit im Job-Alltag, professionelles PC-Wissen und Coaching \u2013 und das vom Bewerbungsfoto bis hin zur kompetenten Gehaltsverhandlung.<\/p> <p>Die ganzt\u00e4gige Fachmesse bietet zudem mit \u00fcber 40 Ausstellern ein breit gef\u00e4chertes Angebot rund um Produkte und Dienstleistungen aus der B\u00fcro- und Karrierewelt. Allen Teilnehmerinnen, die sich auf der Suche nach neuen beruflichen Herausforderungen befinden, bietet der Veranstalter den bew\u00e4hrten, professionellen Bewerbungsmappen-Check an.<\/p> <p>Die Ausstellerliste, das vollst\u00e4ndige Veranstaltungsprogramm und das Anmeldeformular f\u00fcr die Messe sowie alle Vortr\u00e4ge, Workshops und Coachings finden Sie auf dem Portal:<\/p> <p>www.careeratoffice.de<\/p> <p>Materialien zum Herunterladen:<\/p> <p>Pressemitteilung   | Programm | Logo<\/p> <p>Der Messeeintritt ist frei. Jeder Workshop kostet 55,00 \u20ac, die Teilnahme f\u00fcr einen Vortrag betr\u00e4gt 25,00 \u20ac. Den Bewerbungsmappen-Check gibt es zum Messesonderpreis von je 13,00 \u20ac. Alle Preise verstehen sich zzgl. gesetzlicher Mehrwertsteuer. Die n\u00e4chste career@office findet am 05. November 2009 in Neuss statt.<\/p> <p>career@office ist eine Marke des Gabler Verlags |  GWV Fachverlage GmbH. GWV Fachverlage ist Teil der Fachverlagsgruppe<br \/> Springer Science+Business Media .<\/p> <p>Kontakt:<br \/> Markus Fertig M.A. | PR-Referent | Gabler Verlag<br \/> Tel. +49 (0)611.7878-181 | Fax +49 (0)611.7878-451<\/p>","protected":false},"excerpt":{"rendered":"<p>Trends, Chancen und Weiterbildung rund um den Arbeitsplatz B\u00fcro bei der career@office 2009 Wiesbaden\/Frankfurt, 01. April 2009. Telefonate f\u00fchren, Briefe schreiben und Kaffee kochen war gestern. Aus der Sekret\u00e4rin ist die Office-Managerin geworden, denn das Berufsbild hat sich radikal ver\u00e4ndert. Wer heute erfolgreich im B\u00fcro arbeiten m\u00f6chte, muss Managementqualit\u00e4ten beweisen. Die diesj\u00e4hrige career@office \u2013 die<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-931","post","type-post","status-publish","format-standard","hentry","category-business-handel-gewerbe"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=931"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/931\/revisions"}],"predecessor-version":[{"id":271455,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/931\/revisions\/271455"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}