{"id":938,"date":"2009-04-10T11:25:21","date_gmt":"2009-04-10T10:25:21","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/unternehmen-stellen-sich-vor-20092010-neu-im-klaus-resch-verlag-erschienen-10938\/"},"modified":"2010-07-26T14:20:54","modified_gmt":"2010-07-26T13:20:54","slug":"unternehmen-stellen-sich-vor-20092010-neu-im-klaus-resch-verlag-erschienen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/unternehmen-stellen-sich-vor-20092010-neu-im-klaus-resch-verlag-erschienen-10938\/","title":{"rendered":"Unternehmen stellen sich vor 2009\/2010 neu im Klaus Resch Verlag erschienen"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"> <dl> <dt><img decoding=\"async\" src=\"http:\/\/www.pressebox.de\/uploads\/images\/196946_200_160.jpg\" alt=\"Unternehmen stellen sich vor\" \/><\/dt> <\/dl> <\/td> <\/tr> <\/tbody> <\/table> <p><strong>Hardcover als Alleinstellungmerkmal in der Branche &#8211; rund 400 Seiten geballte Unternehmenstradition in hochwertigem Design <\/strong><\/p> <dl> <dd>Unternehmen stellen sich vor<\/dd> <\/dl> <p class=\"text\">(pressebox) Gro\u00dfenkneten, 09.04.2009, Zu Beginn des Sommersemesters ver\u00f6ffentlicht der Klaus Resch Verlag Anfang April erneut seine beliebte Jahrespublikation &#8222;Unternehmen stellen sich vor&#8220;, den informativen Karriereplaner f\u00fcr Studenten, Absol- venten und Young Professionals aller Fachrichtungen.<!--more--><\/p> <p>In nur einem Jahr ist das &#8222;gr\u00fcne Buch&#8220; des Verlages um das dreifache an Beitr\u00e4gen und um 226 Seiten angewachsen. Damit pr\u00e4sentiert &#8222;Unternehmen stellen sich vor&#8220; auf inzwischen rund 400 Seiten \u00fcber 100 umfangreiche Unternehmenshistorien und 100 Firmenportraits mit hilfreichen Angaben f\u00fcr die Bewerbung.<\/p> <p>Als Hardcover-Version und mit neuer Optik versehen setzt sich der Verlag wieder einmal als erster in der Branche von seinen Mitbewerbern ab. Das traditionell quadratische Format als Erkennungszeichen der B\u00fccher von berufsstart.de bleibt bestehen.<\/p> <p>Durch das neue Outfit wird der Lexikoncharakter des Buches noch deutlicher hervorgehoben. Als Allrounder stellt es kleine und gro\u00dfe Arbeitgeber gleicherma\u00dfen attraktiv dar, wie traditionelle Konzerne und junge Startups.<\/p> <p>Rezensionsexemplare k\u00f6nnen beim Verlag angefordert werden.<\/p> <p><strong>Klaus Resch Verlag<\/strong><br \/> Moorbeker Stra\u00dfe 31<br \/> D 26197 Gro\u00dfenkneten<br \/> <span style=\"text-decoration: underline;\">www.berufsstart.de<\/span><\/p> <p style=\"margin-bottom: 8px;\">Telefon                        +49 (4435) 9612-0<\/p> <p class=\"text\">","protected":false},"excerpt":{"rendered":"<p>Hardcover als Alleinstellungmerkmal in der Branche &#8211; rund 400 Seiten geballte Unternehmenstradition in hochwertigem Design Unternehmen stellen sich vor (pressebox) Gro\u00dfenkneten, 09.04.2009, Zu Beginn des Sommersemesters ver\u00f6ffentlicht der Klaus Resch Verlag Anfang April erneut seine beliebte Jahrespublikation &#8222;Unternehmen stellen sich vor&#8220;, den informativen Karriereplaner f\u00fcr Studenten, Absol- venten und Young Professionals aller Fachrichtungen.<\/p>\n","protected":false},"author":1,"featured_media":199047,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arbeit-erziehung-bildung"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=938"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/938\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/199047"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}