{"id":9551,"date":"2010-08-26T17:24:40","date_gmt":"2010-08-26T16:24:40","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=9551"},"modified":"2014-09-10T15:00:24","modified_gmt":"2014-09-10T14:00:24","slug":"steuerrueckerstattung-spanien","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/steuerrueckerstattung-spanien-109551\/","title":{"rendered":"B\u00fcrgern der EU stehen Steuerr\u00fcckerstattungen in Spanien zu"},"content":{"rendered":"<p>Der spanische Fiskus hat Ausl\u00e4nder beim Verkauf ihrer Immobilien jahrelang zu hoch besteuert, dadurch drohen dem Staat Klagen in Millionenh\u00f6he.<br \/> Privatpersonen, die in Spanien zwischen Anfang 1997 und Ende 2006 eine Immobilie verkauft haben, die Sie nicht als ersten Wohnsitz nutzten, sind berechtigt, einen Gro\u00dfteil der bezahlten Steuer in Spanien r\u00fcckerstattet zu bekommen.<!--more--><br \/> Nach einer Entscheidung des Europ\u00e4ischen Gerichtshofs stehen B\u00fcrgern aus der EU, sowie der Schweiz, die zwischen Anfang 1997 und Ende 2006 eine Immobilie in Spanien verkauft haben, Steuerr\u00fcckzahlungen zu.<br \/> Das Gericht entschied, dass die spanische Regierung die Ver\u00e4u\u00dferungsgewinne nicht-spanischer, privater Verk\u00e4ufer zu Unrecht mit 35 Prozent besteuert hatte, da Spanier hingegen auf die Gewinne ihrer Verk\u00e4ufe nur 15 Prozent Steuern zahlen mussten. Nach Ansicht der EU-Instanz ist die unterschiedliche steuerliche Behandlung f\u00fcr die ausl\u00e4ndischen Immobilienbesitzer diskriminierend, deshalb haben diese ein Anrecht auf entsprechende R\u00fcckzahlungen (EuGH Aktenzeichen C-562\/07).<br \/> Die in Valencia ans\u00e4ssige Anwaltskanzlei, Costa, Alvarez, Manglano &amp; Associates, die die Interessen der Betroffenen vertritt, hat f\u00fcr die ersten 100 europ\u00e4ischen B\u00fcrger, zumeist aus Gro\u00dfbritannien, bereits R\u00fcckzahlungen vom spanischen Staat erhalten. F\u00fcr den deutschsprachigen Raum wurde in Deutschland eine Anlaufstelle eingerichtet.<br \/> Rund 150 000 ehemalige Immobilienbesitzer, so wird vermutet, k\u00f6nnten Anrecht auf diese R\u00fcckforderungen haben. Im Schnitt d\u00fcrften bis zu 20 000 Euro erstattet werden.<br \/> Der Countdown l\u00e4uft allerdings. Anspr\u00fcche m\u00fcssen innerhalb eines Jahres nach der Urteilsverk\u00fcndung geltend gemacht werden. Antr\u00e4ge auf R\u00fcckerstattung k\u00f6nnen daher nur bis Mitte November bei spanischen Gerichten eingereicht werden.<br \/> Aus diesem Grund ist f\u00fcr alle Informationen, Fragen sowie Kontaktm\u00f6glichkeiten die deutsche Internetseite www.steuer-spanien.info f\u00fcr die Betroffenen geschaltet worden.<\/p> <p>Kontaktinformation:<br \/> B\u00f6cker GbR<br \/> Louisenstra\u00dfe 52<br \/> 61348 Bad Homburg<br \/> Kontakt-Person:<br \/> Benjamin B\u00f6cker<br \/> Telefon: 06172-456433<br \/> E-Mail: e-Mail<br \/> Web: http:\/\/www.steuer-spanien.info<\/p>","protected":false},"excerpt":{"rendered":"<p>Der spanische Fiskus hat Ausl\u00e4nder beim Verkauf ihrer Immobilien jahrelang zu hoch besteuert, dadurch drohen dem Staat Klagen in Millionenh\u00f6he. Privatpersonen, die in Spanien zwischen Anfang 1997 und Ende 2006 eine Immobilie verkauft haben, die Sie nicht als ersten Wohnsitz nutzten, sind berechtigt, einen Gro\u00dfteil der bezahlten Steuer in Spanien r\u00fcckerstattet zu bekommen.<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-9551","post","type-post","status-publish","format-standard","hentry","category-recht-wirtschaft-steuerberatung"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/9551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=9551"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/9551\/revisions"}],"predecessor-version":[{"id":172492,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/9551\/revisions\/172492"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=9551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=9551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=9551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}