{"id":965,"date":"2009-04-25T08:24:19","date_gmt":"2009-04-25T07:24:19","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/die-neue-raumzeit-ist-da-am-294-am-kiosk-10965\/"},"modified":"2010-07-26T14:20:49","modified_gmt":"2010-07-26T13:20:49","slug":"die-neue-raumzeit-ist-da-am-294-am-kiosk","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/die-neue-raumzeit-ist-da-am-294-am-kiosk-10965\/","title":{"rendered":"Die neue raum+zeit ist da! Am 29.4 am Kiosk!"},"content":{"rendered":"<p><strong>Die Ausgabe Nr. 159 der raum&amp;zeit hat folgende spannende Themen:<\/strong><\/p> <p><strong>Ferngesteuerte Kinder \u2013 Psychopillen werden zu leichtfertig verschrieben<\/strong><br \/> Kinder sind zu einer der interessantesten Zielgruppen der Psychopharmaka-Hersteller avanciert. Bieten sie doch jede Menge noch unerschlossener Absatzm\u00f6glichkeiten. Im Bereich psychischer Krankheiten ist es zudem beinahe kinderleicht, die Definitionen von Krankheiten auszuweiten.<!--more--> Wo beginnen beispielsweise Unaufmerksamkeit und Impulsivit\u00e4t krankhaft zu werden? Pharmakonzerne setzen ausgekl\u00fcgelte Marketingstrategien ein, um diese Grenzen herabzusetzen. Sie \u00fcberbieten sich gegenseitig mit der Erfindung schwerer Chemiekeulen gegen leichte St\u00f6rungen. Diese Substanzen k\u00f6nnen aber verheerende Auswirkungen auf die sensiblen Kindergehirne haben. M\u00fcssen unsere Kinder vor dem langen Arm der Konzerne gesch\u00fctzt werden?<\/p> <p><strong>Die Blauzungenkrankheit. Verbreitet Massenimpfung die Seuche?<\/strong><br \/> Im August 2006 gab es den ersten Fall eines merkw\u00fcrdig erkrankten Rindes in Deutschland. Diagnose: Blauzungenkrankheit. Anschlie\u00dfend wurden die Bauern verpflichtet, ihre Rinder, Schafe und Ziegen impfen zu lassen. Mit \u00e4u\u00dferst fragw\u00fcrdigen Impfstoffen, die weder zugelassen noch ausreichend getestet waren. Teilweise auch noch auf fahrl\u00e4ssige Weise. Viele Tier\u00e4rzte benutzen zum Beispiel zum Impfen eines Tierbestandes nur eine Kan\u00fcle und \u00fcbertrugen damit teilweise die Krankheit. So ist es kein Wunder, dass zahlreiche Landwirte beobachten mussten, dass ihre Tiere kurz nach den Impfungen krank wurden, Aborte hatten oder sogar starben. Eine Sprecherin der Interessengemeinschaft f\u00fcr gesunde Tiere (IggT) schl\u00e4gt Alarm.<\/p> <p><strong>Maya-Kalender neu berechnet. Keine Angst vor 2012<\/strong><br \/> Am 21. Dezember 2012 endet bekanntlich der Maya-Kalender. Dieser Tag gilt vielen Menschen als einschneidendes Datum, an dem sich das Schicksal der Menschheit entscheiden wird. Manche erwarten eine kosmische Katastrophe, dem j\u00fcngsten Tag der Bibel vergleichbar. Doch was ist, wenn derartige Vorhersagen auf einem Fehler in der Kalenderinterpretation beruhen? Ein profunder Kenner alter Pyramidenkulturen zeigt auf, warum wir uns vor diesem \u00e4ngstlich erwarteten Datum nicht f\u00fcrchten sollten.<\/p> <p>Neben diesen Artikeln gibt es viele andere interessante Beitr\u00e4ge in der neuen Ausgabe der raum&amp;zeit zu entdecken, wie beispielsweise \u201eRegierung verharmlost Krebs-Gefahr durch Atomkraftwerke\u201c, \u201eCodex Alimentarius. Weltumspannender Lebensmittel-Imperialismus\u201c oder \u201eSchatten auf Goethes Farbenlehre. Einw\u00e4nde gegen das \u201aUrph\u00e4nomen\u2019 des Dichterf\u00fcrsten\u201c.<\/p> <p>Die Zeitschrift raum&amp;zeit berichtet seit \u00fcber 20 Jahren kritisch \u00fcber Naturwissenschaften, Medizin, Politik und Philosophie und zeigt in all diesen Bereichen hoffnungsvolle Alternativen auf. Sie bietet ein Forum f\u00fcr wichtige Erkenntnisse, die oftmals keinen Einlass in die \u00f6ffentliche Diskussion finden.<\/p> <p>Sie erhalten die Zeitschrift in fast jeder Bahnhofsbuchhandlung oder direkt beim Ehlers Verlag.<\/p> <p>Ehlers Verlag GmbH<br \/> Geltinger Str. 14 e<br \/> 82515 Wolfratshausen<br \/> Ansprechpartner: Andrea Ehlers<br \/> Tel.: 08171\/4184\/77<br \/> Fax:\u00a0 08171\/4184\/66<br \/> e-mail: andrea@ehlersverlag.de<\/p> <p>Bei vertrieblichen R\u00fcckfragen wenden Sie sich bitte an:<br \/> Angela W\u00f6lky, Tel.: 08171\/41 84 61, Fax: 08171\/41 84 66, e-mail: vertrieb@ehlersverlag.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Die Ausgabe Nr. 159 der raum&amp;zeit hat folgende spannende Themen: Ferngesteuerte Kinder \u2013 Psychopillen werden zu leichtfertig verschrieben Kinder sind zu einer der interessantesten Zielgruppen der Psychopharmaka-Hersteller avanciert. Bieten sie doch jede Menge noch unerschlossener Absatzm\u00f6glichkeiten. Im Bereich psychischer Krankheiten ist es zudem beinahe kinderleicht, die Definitionen von Krankheiten auszuweiten.<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1027,1028,210,1029],"class_list":["post-965","post","type-post","status-publish","format-standard","hentry","category-allgemein-sonstiges","tag-blauzungenkrankheit","tag-psychopillen","tag-raumzeit","tag-ritalin"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=965"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/965\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}