{"id":967,"date":"2009-04-25T10:33:33","date_gmt":"2009-04-25T09:33:33","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/erfolgreiches-marketing-selbstbewusst-und-innovativ-die-chancen-in-der-krise-nutzen-10967\/"},"modified":"2010-07-26T14:20:48","modified_gmt":"2010-07-26T13:20:48","slug":"erfolgreiches-marketing-selbstbewusst-und-innovativ-die-chancen-in-der-krise-nutzen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/erfolgreiches-marketing-selbstbewusst-und-innovativ-die-chancen-in-der-krise-nutzen-10967\/","title":{"rendered":"erfolgreiches Marketing-Selbstbewusst und innovativ die Chancen in der Krise nutzen"},"content":{"rendered":"<p>Frankfurt\/M. \/ Berlin (ots) -Experten diskutieren auf dem MMD 09 die Perspektiven f\u00fcr<br \/> erfolgreiches Marketing \/ Inhalte, Marken, Innovationen und<br \/> Emotionalit\u00e4t als Erfolgsfaktoren f\u00fcr den Wettbewerb Bei der Analyse der aktuellen gesamtwirtschaftlichen Malaise waren<br \/> sich die Experten auf dem 2. MMD Magazine Marketing Day einig: Ein\u00a0 &#8222;annus horribilis&#8220;, ein finsteres Jahr, erwartet etwa Burda-Vorstand\u00a0 Philipp Welte. <!--more-->Um bis zu sieben Prozent k\u00f6nne die deutsche Wirtschaft<br \/> in 2009 schrumpfen. \u00c4hnliche Szenarien sehen auch Udo Klein-B\u00f6lting,<br \/> Partner BBDO Consulting und Spiegel-Chefredakteur Mathias M\u00fcller von<br \/> Blumencron auf die Wirtschaft hierzulande zukommen. Doch trotz dieser<br \/> schwierigen gesamtwirtschaftlichen Rahmenbedingungen und einer, so<br \/> Welte, &#8222;Rezession nie gekannten Ausma\u00dfes&#8220; er\u00f6ffnen sich f\u00fcr das<br \/> Marketing, die Medien und vor allem die Zeitschriftenbranche auch<br \/> enorme Chancen.<\/p> <p>Zwar erodiert die Rezession in den Augen von Philipp Welte<br \/> unzweifelhaft das Stammgesch\u00e4ft der Verlage, und der Strukturwandel<br \/> der Branche habe zu einer gewaltigen Un\u00fcbersichtlichkeit gef\u00fchrt,<br \/> doch die Zeitschriftenbranche verf\u00fcge \u00fcber vier Kernfaktoren, die sie<br \/> im digitalen Wandel nachhaltig st\u00e4rkt: Sie verf\u00fcgt \u00fcber die<br \/> redaktionellen Inhalte, die bekannten Medienmarken, die F\u00e4higkeit zur<br \/> Innovation und die hohe Emotionalit\u00e4t. Dieser Profi generated Content<br \/> mache die Einzigartigkeit der Branche aus und verschaffe ihr im<br \/> Wettbewerb gro\u00dfe Chancen: Allein \u00fcber 13.000 fest angestellte<br \/> Journalisten bei Printmedien gew\u00e4hrleisten Glaubw\u00fcrdigkeit und<br \/> Recherchetiefe, ohne die die Skandale dieser Republik wohl kaum ans<br \/> Licht gekommen w\u00e4ren. Zugleich appellierte Welte an die Verlage, die<br \/> Konvergenz als die gro\u00dfe Herausforderung an journalistische Kompetenz<br \/> und Innovation anzunehmen: &#8222;Wir m\u00fcssen uns \u00fcber technogene Grenzen<br \/> hinaus weiterentwickeln und die technologieneutralen Strategien<br \/> forcieren. Mit unserer F\u00e4higkeit, Marken zu machen, haben wir in der<br \/> Digitalisierung gute Chancen.&#8220;<\/p> <p>Auch M\u00fcller von Blumencron warnte vor Schwarzmalerei: &#8222;Weg mit der<br \/> Weinerlichkeit in diesen Tagen der Krise &#8211; wir leben in einer Zeit<br \/> der Wissensgesellschaft, mit riesigen Chancen f\u00fcr die<br \/> Zeitschriftenmarken. Wir d\u00fcrfen uns daher auch nicht unser eigenes<br \/> Grab herbeischreiben.&#8220; Wie zuvor Philipp Welte pl\u00e4dierte M\u00fcller von<br \/> Blumencron f\u00fcr eine medienneutrale Sichtweise: &#8222;Es ist unsinnig, eine<br \/> Konkurrenzdebatte zwischen Print oder Online zu f\u00fchren, es kann nur<br \/> eine Sichtweise geben, die relevant ist, und die hei\u00dft: Journalismus<br \/> first.&#8220; Daher m\u00fcsse man die ver\u00e4nderten Leser- und<br \/> Nutzungsgewohnheiten ernst nehmen. Es sei daher nur logisch, dass der<br \/> Journalismus insgesamt noch aktueller, multimedialer und dialogisch<br \/> geworden sei. Die Perspektive der Verlagsvertreter fand Best\u00e4tigung<br \/> in der Sichtweise Hubertus von Lobensteins, CEO TBWA Deutschland:<br \/> &#8222;Das kollektive Jammern baut nirgendwo Vertrauen auf.&#8220; In einer Zeit,<br \/> in der Produkte und Marken auf eine schier un\u00fcbersichtliche Zahl<br \/> angewachsen sind und Einzigartigkeit auch im Zeitschriftenregal immer<br \/> schwieriger wird, sei es notwendig, dass Marken ihre<br \/> zielgruppenspezifische Relevanz noch st\u00e4rker profilieren:<br \/> &#8222;diffentiate and win&#8220;, so Lobenstein. Da sich die Menschen ihre<br \/> eigene Kommunikationsrealit\u00e4t schafften, m\u00fcssen die Medien \u00fcber die<br \/> Emotion die Aufmerksamkeit der Menschen auf sich ziehen.<\/p> <p>Das komplette Programm und alle Informationen rund um den Magazine<br \/> Marketing Day finden Sie unter www.magazine-marketing-day.de .<\/p> <p>Originaltext:         VDZ Verband Deutscher Zeitschriftenverleger<\/p> <p>Weitere Informationen:<br \/> Norbert R\u00fcdell<br \/> Leiter Presse und Kommunikation<br \/> Tel.:     +49 (30) 72 62 98-162<br \/> E-Mail:   n.ruedell@vdz.de<br \/> Internet: www.vdz.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Frankfurt\/M. \/ Berlin (ots) -Experten diskutieren auf dem MMD 09 die Perspektiven f\u00fcr erfolgreiches Marketing \/ Inhalte, Marken, Innovationen und Emotionalit\u00e4t als Erfolgsfaktoren f\u00fcr den Wettbewerb Bei der Analyse der aktuellen gesamtwirtschaftlichen Malaise waren sich die Experten auf dem 2. MMD Magazine Marketing Day einig: Ein\u00a0 &#8222;annus horribilis&#8220;, ein finsteres Jahr, erwartet etwa Burda-Vorstand\u00a0 Philipp<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-967","post","type-post","status-publish","format-standard","hentry","category-marketing-werbung-pr-design"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=967"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/967\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}