{"id":97152,"date":"2013-09-30T16:38:07","date_gmt":"2013-09-30T16:38:07","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=97152"},"modified":"2025-05-30T10:49:10","modified_gmt":"2025-05-30T09:49:10","slug":"krebstherapie-heute-schwerpunkte-der-biologischen-krebstherapie","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/krebstherapie-heute-schwerpunkte-der-biologischen-krebstherapie-1097152\/","title":{"rendered":"Krebstherapie heute &#8211; Schwerpunkte der biologischen Krebstherapie"},"content":{"rendered":"<div> <p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-97470\" title=\"das medizinische Online-Portal\" alt=\"das medizinische Online-Portal\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/48124698adb2a627e1513b2852454a23.png\" width=\"200\" height=\"59\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/48124698adb2a627e1513b2852454a23.png\" \/>Biologische Krebstherapie erg\u00e4nzt konservative Krebstherapie<\/p> <p>Das wachsende Wissen um die biologische Krebstherapie verbessert ihren Stellenwert im Vergleich zur konservativen Krebstherapie kontinuierlich.<\/p> <p>Ob Darmkrebs, Lungenkrebs oder Hautkrebs &#8211; auf internationalen Kongressen diskutieren Mediziner aus Forschung, Klinik und Praxis laufend \u00fcber neue M\u00f6glichkeiten zur Behandlung aller Krebsarten, tauschen sich aus und entwickeln neue Behandlungsans\u00e4tze. Heute stehen bei vielen Krebserkrankungen neben der operativen Entfernung des Tumors, der Bestrahlung und der Chemotherapie erfolgreiche biologische Ans\u00e4tze erg\u00e4nzend zur Verf\u00fcgung. <!--more-->Das wachsende Wissen um die biologische Krebstherapie verbessert ihren Stellenwert im Vergleich zur konservativen Krebstherapie kontinuierlich. Prof. Dr. med. J\u00fcrgen Wolf, Leiter des Centrums f\u00fcr Integrierte Onkologie an der Uniklinik K\u00f6ln erl\u00e4utert im Webcast-Interview im eJournal MEDIZIN ASPEKTE ( www.medizin-aspekte.de (http:\/\/www.medizin-aspekte.de) ) die drei S\u00e4ulen der biologisch rationalen Krebstherapie und beschreibt ihren Stellenwert im Vergleich zur konservativen Krebstherapie. Das Webcastinterview mit Prof. Dr. med. J. Wolf tr\u00e4gt den Titel: Krebstherapie heute &#8211; Schwerpunkte der biologischen Krebstherapie (http:\/\/www.medizin-aspekte.de\/movie\/Krebs_317_1.html)<\/p> <p>MEDIZIN ASPEKTE ist ein monatlich erscheinendes Journal. MEDIZIN ASPEKTE informiert Patienten und Angeh\u00f6rige \u00fcber Krankheiten und Therapieoptionen. Einen besonderen Fokus bildet die Pr\u00e4vention. Medienschwerpunkte liegen sowohl in der Berichterstattung als auch in den Bereichen Experten.TV, Experten-Interviews, Launch-Talks, Image-Filme sowie Veranstaltungsdokumentationen.<\/p> <p>Kontakt<br \/> Redaktion MEDIZIN ASPEKTE \/ MCP Wolff GmbH<br \/> Martina Wolff<br \/> Gugelstr. 5<br \/> 67549 Worms<br \/> 06241- 955421<br \/> info@mcp-wolff.de<br \/> http:\/\/medizin-aspekte.de<\/p> <p>Pressekontakt:<br \/> Redaktion MEDIZIN ASPEKTE \/ MCP Wolff GmbH<br \/> Martina Wolff<br \/> Gugelstr. 5<br \/> 67549 Worms<br \/> 06241-955421<br \/> redaktion@medizin-aspekte.de<br \/> http:\/\/medizin-aspekte.de<\/p> <p>&nbsp;<\/p> <\/div>","protected":false},"excerpt":{"rendered":"<p>Biologische Krebstherapie erg\u00e4nzt konservative Krebstherapie Das wachsende Wissen um die biologische Krebstherapie verbessert ihren Stellenwert im Vergleich zur konservativen Krebstherapie kontinuierlich. Ob Darmkrebs, Lungenkrebs oder Hautkrebs &#8211; auf internationalen Kongressen diskutieren Mediziner aus Forschung, Klinik und Praxis laufend \u00fcber neue M\u00f6glichkeiten zur Behandlung aller Krebsarten, tauschen sich aus und entwickeln neue Behandlungsans\u00e4tze. Heute stehen bei<\/p>\n","protected":false},"author":3,"featured_media":196914,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[1734],"class_list":["post-97152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medizin-gesundheit-pflege-soziales","tag-default"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/97152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=97152"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/97152\/revisions"}],"predecessor-version":[{"id":277500,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/97152\/revisions\/277500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/196914"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=97152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=97152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=97152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}