{"id":981,"date":"2009-05-01T10:05:39","date_gmt":"2009-05-01T09:05:39","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/suizid-warte-bis-du-gehst-10981\/"},"modified":"2010-07-26T14:20:45","modified_gmt":"2010-07-26T13:20:45","slug":"suizid-warte-bis-du-gehst","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/suizid-warte-bis-du-gehst-10981\/","title":{"rendered":"Suizid &#8211; Warte, bis Du gehst!"},"content":{"rendered":"<p>Welche Ursachen einen Suizid ausl\u00f6sen k\u00f6nnen und warum auch<br \/> Depressionen und Mobbing so gef\u00e4hrlich\u00a0sind, beschreibt<br \/> Fachbuchautor Mikel Marz in diesem neuen Buch, mit notwendigen<br \/> Informationen und Ratschl\u00e4gen, sowie\u00a0mit wahren Ereignissen.<br \/> Man geht alleine nur in Deutschland davon aus, dass sich j\u00e4hrlich ca. 12000<br \/> Menschen das Leben nehmen. Eine Zahl, die sehr betroffen und nachdenklich<br \/> macht, vor allem wenn man wei\u00df, dass 85 Prozent der Opfer ihre Tat vorher<br \/> angek\u00fcndigt hatten.<!--more--><\/p> <p>Doch welche Gr\u00fcnde sind so schlimm, dass Menschen keinen Ausweg mehr f\u00fcr ihr<\/p> <p>Leben sehen und warum konnte ihnen nicht geholfen werden?<\/p> <p>Ich m\u00f6chte dieses Thema, die Ursachen und auch die einzelnen Gefahren n\u00e4her<\/p> <p>unter die Lupe nehmen, weil auch ich schon am Abgrund stand und einen Retter in<\/p> <p>der Not hatte, f\u00fcr den ich heute noch immer sehr dankbar bin.<\/p> <p>Deshalb wurden auch viele Geschichten von Betroffenen mit in dieses Buch<\/p> <p>eingef\u00fcgt, um Ihnen zu zeigen, dass auch andere Menschen dem Leben noch eine<\/p> <p>Chance gebeben haben und wie leicht es manchmal sein kann, ein Problem zu<\/p> <p>l\u00f6sen.<\/p> <p>Nicht umsonst wurde darum der Titel gew\u00e4hlt:<\/p> <p>Suizid \u2013 Warte, bis Du gehst!<\/p> <p>Im Handel erh\u00e4ltlich, www.buchhandel.de oder im www.roderer-verlag.de<\/p> <p>ISBN 978-3-89783-658-7\u00a0\u00a0\u00a0\u00a0 \/\u00a0\u00a0\u00a0 Preis: 16,80 EUR<\/p> <p>Informationen unter: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.mikelmarz.de\/\"  >www.mikelmarz.de<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Welche Ursachen einen Suizid ausl\u00f6sen k\u00f6nnen und warum auch Depressionen und Mobbing so gef\u00e4hrlich\u00a0sind, beschreibt Fachbuchautor Mikel Marz in diesem neuen Buch, mit notwendigen Informationen und Ratschl\u00e4gen, sowie\u00a0mit wahren Ereignissen. Man geht alleine nur in Deutschland davon aus, dass sich j\u00e4hrlich ca. 12000 Menschen das Leben nehmen. Eine Zahl, die sehr betroffen und nachdenklich macht,<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1054,1053,1052,1057,1051,1055,1056],"class_list":["post-981","post","type-post","status-publish","format-standard","hentry","category-allgemein-sonstiges","tag-burnout","tag-depression","tag-marz","tag-mikel-marz","tag-mobbing","tag-posttraumatische-belastungsstorung","tag-suizid"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=981"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/981\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}