{"id":9915,"date":"2010-09-08T15:39:09","date_gmt":"2010-09-08T14:39:09","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=9915"},"modified":"2010-09-08T15:39:09","modified_gmt":"2010-09-08T14:39:09","slug":"ausgabe-magazin","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/ausgabe-magazin-109915\/","title":{"rendered":"Den eigenen Traum leben"},"content":{"rendered":"<table style=\"float: left; height: 123px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\" width=\"86\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9918\" title=\"je2.jpg\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/9915\/je2.jpg\" alt=\"\" width=\"86\" height=\"124\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Seit Mitte August gibt es die neue \u201eJETZT ERFOLGREICH!\u201c. Mit dem Thema \u201eDen eigenen Traum leben\u201c greift Herausgeber Stephan Landsiedel in der zweiten Ausgabe ein Thema auf, dass ihn schon \u00fcber l\u00e4ngere Zeit besch\u00e4ftigt. Bereits vor zehn Jahren ver\u00f6ffentlichte er sein erstes Buch \u201eWay up \u2013 den eigenen Traum leben\u201c, in dem er seine Leser motivierend f\u00f6rdert, sich mutig zu ihrem eigenen Traum zu bekennen, an ihn zu glauben und ihn Schritt f\u00fcr Schritt Wirklichkeit werden zu lassen.<!--more--><br \/> Der begeisternde und mitreisende Schreibstil des Diplom-Psychologen macht auch diese Ausgabe wieder zu einem kurzweiligen Leseerlebnis mit vielen Impulsen und Anregungen. Neben  neuen Gedankenanst\u00f6\u00dfen werden konstruktive Strategien und Modelle vorgestellt, die helfen, ein bestimmtes Ziel Schritt f\u00fcr Schritt anzugehen. So werden beispielsweise die sieben Phasen der Engpasskonzentrierten Strategie (EKS) beschrieben sowie die Vorgehensweise bei der \u00dcbung \u201eTraum-Workshop\u201c. Alle Abonnenten des Magazins genie\u00dfen au\u00dferdem online unter jetzt-erfolgreich.com viele kostenlose Zusatzleistungen wie zum Beispiel H\u00f6rb\u00fccher zum gratis Download sowie weiterf\u00fchrende Artikel zur Zeitschrift.<br \/> Das handliche Magazin im DIN A5-Format soll f\u00fcr die Leser als kleiner Begleiter fungieren, der sie bei ihrem pers\u00f6nlichen Erfolgstraining unterst\u00fctzt. F\u00fcr alle, die viel unterwegs sind und selten zum Lesen kommen, gibt es \u201eJETZT ERFOLGREICH!\u201c auch als H\u00f6r-Magazin. Mehr Informationen, eine Leseprobe sowie das Bestellformular zum Gratisexemplar der ersten Ausgabe, gibt es unter <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.jetzt-erfolgreich.com\"  >www.jetzt-erfolgreich.com<\/a>.<\/p> <p>Landsiedel NLP Training<br \/> Neustadtstra\u00dfe 10<br \/> D-97353 Wiesentheid<br \/> Tel. 09383 &#8211; 90 13 14<br \/> E-Mail: info@landsiedel.com<br \/> Internet: www.landsiedel-seminare.de<\/p> <p>Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a7 27 a Umsatzsteuergesetz: DE 205-243-20291<br \/> Inhaltlich Verantwortlicher gem\u00e4\u00df \u00a7 6 MDStV:<br \/> Stephan Landsiedel<br \/> Rechtsform von Landsiedel NLP Training: Einzelfirma.<\/p>","protected":false},"excerpt":{"rendered":"<p>Seit Mitte August gibt es die neue \u201eJETZT ERFOLGREICH!\u201c. Mit dem Thema \u201eDen eigenen Traum leben\u201c greift Herausgeber Stephan Landsiedel in der zweiten Ausgabe ein Thema auf, dass ihn schon \u00fcber l\u00e4ngere Zeit besch\u00e4ftigt. Bereits vor zehn Jahren ver\u00f6ffentlichte er sein erstes Buch \u201eWay up \u2013 den eigenen Traum leben\u201c, in dem er seine Leser<\/p>\n","protected":false},"author":291,"featured_media":9918,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-9915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arbeit-erziehung-bildung"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/9915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=9915"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/9915\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/9918"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=9915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=9915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=9915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}