{"id":997,"date":"2009-05-08T13:56:23","date_gmt":"2009-05-08T12:56:23","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/selber-machen-garten-zeigt-wie-es-geht-10997\/"},"modified":"2012-09-24T15:28:50","modified_gmt":"2012-09-24T14:28:50","slug":"selber-machen-garten-zeigt-wie-es-geht","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/selber-machen-garten-zeigt-wie-es-geht-10997\/","title":{"rendered":"SELBER MACHEN-Garten zeigt, wie es geht"},"content":{"rendered":"<p>Gourmet Gardening liegt voll im Trend &#8211;<br \/> Familie Obama hat es mit dem Anlegen eines Gem\u00fcsegartens im\u00a0 Garten des Wei\u00dfen Hauses in Washington vorgemacht: Der Eigenanbau von Gem\u00fcse &#8211; das Gourmet Gardening &#8211; liegt voll im Trend.Das SELBER MACHEN-Garten-Spezial aus dem Hamburger JAHRESZEITEN VERLAG zeigt alle Tipps und Tricks, die dabei zu beachten sind.<!--more--><\/p> <p>Neben dem richtigen Standort sollte der G\u00e4rtner beim Anlegen eines heimischen Gem\u00fcsegartens vor allem auf die richtige Pflanzenkombination achten, um so wichtige Synergieeffekte zu nutzen. Die unkonventionelle Zusammenstellung eines Beetes aus Blumen und Gem\u00fcse, Obst, Rosen und Kr\u00e4utern l\u00e4sst n\u00fctzliche Synergien wie gegenseitige Wachstumsf\u00f6rderung oder gemeinsame Sch\u00e4dlingsbek\u00e4mpfung entstehen. Chefredakteur Thomas Mauz, \u201eDas Zauberwort im Gem\u00fcseanbau lautet Mischkultur &#8211; dieser neue Trend wird die G\u00e4rten Deutschlands nicht nur h\u00fcbsch aussehen lassen, sondern auch dazu f\u00fchren, dass das Gem\u00fcse gesund und frisch auf den<br \/> Tisch kommt. Daher auch der neue Begriff \u201eGourmet Gardening.&#8220;<\/p> <p>Tipps und Anregungen zu diesem Thema stehen in der am 8. Mai 2009 erscheinenden Ausgabe SELBER MACHEN GARTEN.<br \/> Hamburg, 07. Mai 2009<br \/> _________________________________________________________<br \/> Pressekontakt: Mona Burmester, Presse und \u00d6ffentlichkeitsarbeit JAHRESZEITEN VERLAG, Tel. 040\/2717-2493, Fax 040\/2717-2063, E-Mail: presse@jalag.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Gourmet Gardening liegt voll im Trend &#8211; Familie Obama hat es mit dem Anlegen eines Gem\u00fcsegartens im\u00a0 Garten des Wei\u00dfen Hauses in Washington vorgemacht: Der Eigenanbau von Gem\u00fcse &#8211; das Gourmet Gardening &#8211; liegt voll im Trend.Das SELBER MACHEN-Garten-Spezial aus dem Hamburger JAHRESZEITEN VERLAG zeigt alle Tipps und Tricks, die dabei zu beachten sind.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-997","post","type-post","status-publish","format-standard","hentry","category-bau-mieter-immobilien"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=997"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/997\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}