{"id":244,"count":1,"description":"","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/tag\/sonderausgabe\/","name":"Sonderausgabe","slug":"sonderausgabe","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags\/244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts?tags=244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}